{"id":26,"date":"2026-03-18T10:44:39","date_gmt":"2026-03-18T10:44:39","guid":{"rendered":"https:\/\/wisedb.com.br\/?post_type=solucoes&#038;p=26"},"modified":"2026-07-14T14:01:52","modified_gmt":"2026-07-14T14:01:52","slug":"cloud-computing","status":"publish","type":"solucoes","link":"https:\/\/wisedb.com.br\/index.php\/solucoes\/cloud-computing\/","title":{"rendered":"Cloud Computing"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"26\" class=\"elementor elementor-26\" data-elementor-post-type=\"solucoes\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86f8381 e-flex e-con-boxed e-con e-parent\" data-id=\"86f8381\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/vimeo.com\\\/1202209885?share=copy&amp;fl=sv&amp;fe=ci&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div><div class=\"elementor-element elementor-element-af5fb0b e-con-full e-flex e-con e-child\" data-id=\"af5fb0b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d204a7 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9d204a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cloud computing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-541d7aa elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"541d7aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transforme sua infraestrutura em vantagem competitiva com uma estrat\u00e9gia Nuvem inteligente e\nresiliente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc0ae62 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bc0ae62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Planejamos, migramos e otimizamos ambientes em nuvem com foco em performance, redu\u00e7\u00e3o de custos e continuidade operacional \u2014 utilizando o melhor de Oracle Cloud, AWS e Azure.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e86f4f e-con-full e-flex e-con e-child\" data-id=\"1e86f4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2af18af e-con-full e-flex e-con e-child\" data-id=\"2af18af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31ca99a elementor-widget elementor-widget-image\" data-id=\"31ca99a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjgzMiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"209\" height=\"50\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/04\/BT-1.svg\" class=\"elementor-animation-sink attachment-large size-large wp-image-851\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cd97a6 e-con-full e-flex e-con e-child\" data-id=\"3cd97a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d493965 e-grid e-con-boxed e-con e-parent\" data-id=\"d493965\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a7ecb2 e-con-full e-flex e-con e-child\" data-id=\"9a7ecb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c53e89f animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c53e89f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8005d4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b8005d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2151_100)\"><path d=\"M26.4999 91.49C3.57993 88.26 -1.01007 55.15 23.2699 45.26C25.1699 44.49 28.1799 44.77 28.8399 44.34C29.4999 43.91 30.2599 38.51 30.9599 36.95C36.6599 24.15 53.2399 17.52 65.5199 25.38C82.8599 -7.47 129.93 1.18999 133.05 38.44C157.16 38.43 167.79 68.94 149.95 84.94C147.7 86.96 139.22 91.5 136.51 91.5H100.01V55C100.01 52.35 97.2799 49.83 94.5599 49.45C90.7599 48.93 74.0499 48.85 70.5399 49.52C69.2299 49.77 66.0199 52.34 66.0199 53V91.5C53.7799 90.26 38.3499 93.17 26.5199 91.5L26.4999 91.49Z\" fill=\"#FF5718\"><\/path><path d=\"M95 54.49V96.49H109C106.14 100.47 85.38 128.08 83.36 128.42C81.71 128.69 79.3 125.02 78.03 123.97L57 96.5H71V54.5H95V54.49Z\" fill=\"#FF5718\"><\/path><path d=\"M7 157.49V108.49H21.5C22.6 108.49 22.93 110.93 23.05 111.94C24.07 120.65 24.07 145.33 23.05 154.04C22.93 155.05 22.59 157.49 21.5 157.49H7Z\" fill=\"#FF5718\"><\/path><path d=\"M134.01 108.49C134.39 108.9 133.44 112.16 134.17 113.35C134.54 113.96 145.24 117.37 143.98 122.91C137.2 128.89 137.08 123.15 134.32 121.45C128.14 117.65 122.14 124.39 126.7 127.58C132.9 131.92 146.21 129.67 143.96 143.95C142.87 150.89 134.89 151.46 134.17 152.66C132.93 154.72 136.56 159.09 128.89 157.95C125.75 157.48 127.82 154.98 126.04 152.99C125.33 152.2 123.14 151.89 122.07 150.95C119.5 148.68 113.19 141.67 119.53 140.49C125.87 139.31 124.56 143.79 127 145.02C130.44 146.76 137.43 144.86 135.91 140.16C134.56 136 116 137.27 116.96 124.02C117.13 121.63 118.78 118.12 120.46 116.45C122.43 114.49 126.69 113.68 126.89 113.38C127.58 112.37 126.62 108.92 127.01 108.5C127.25 108.24 133.78 108.24 134.02 108.5L134.01 108.49Z\" fill=\"#FF5718\"><\/path><path d=\"M42.9999 157.49H28.4999C27.3999 157.49 27.0699 155.05 26.9499 154.04C26.5199 150.41 26.4099 124.32 27.1399 122.13C28.0899 119.26 42.9999 120.03 42.9999 121.99V157.49Z\" fill=\"#FF5718\"><\/path><path d=\"M63 132.49V157.49H48.5C47.4 157.49 47.07 155.05 46.95 154.04C46.54 150.53 46.41 138.2 47 134.99C47.15 134.16 47.8 132.49 48.5 132.49H63Z\" fill=\"#FF5718\"><\/path><path d=\"M67.9999 157.49C68.4699 154.61 66.9299 145.33 68.9399 143.93C70.2399 143.02 82.5999 143.04 83.5699 144.43C84.5999 145.92 84.4899 157.49 82.5099 157.49H68.0099H67.9999Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2151_100\"><rect width=\"151.86\" height=\"153.12\" fill=\"white\" transform=\"translate(7 5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-113b53c animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"113b53c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Redu\u00e7\u00e3o de custos com cloud atrav\u00e9s de otimiza\u00e7\u00e3o e governan\u00e7a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be9b1ef e-con-full e-flex e-con e-child\" data-id=\"be9b1ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9b1948 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a9b1948\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc0cf70 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bc0cf70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2151_110)\"><path d=\"M126.94 106.08C131.23 95.46 135.55 84.66 137.66 73.31C138.66 67.95 141.93 38.61 138.97 36.54C138.03 35.88 120.29 31.95 116.71 30.8C105.09 27.05 93.78 22.35 82.34 18.09C63.45 24.64 44.88 33.39 24.93 36.09C22.92 73.19 30.89 107.91 60.45 132.06C64.38 135.27 79.29 146.67 83.63 145.34C86.89 144.34 92.03 139.27 94.88 138.51C97.38 137.85 97.8 149.41 97.47 150.07C96.84 151.33 84.93 157.67 83.15 157.9C78.92 158.47 66.64 150.56 62.6 147.89C24.99 123 7.68001 77.15 12.91 32.56C13.31 29.13 13.77 27.94 17.1 26.75C26.57 23.35 39.14 21.53 49.47 18.12C56.02 15.96 77.06 6.19 81.45 6C86.07 5.8 108.5 16.18 115.14 18.36C120.28 20.05 148.02 26.71 149.49 28.01C152.63 30.81 149.66 39.49 151.83 43.68C150.57 66.13 148.52 88.42 137.95 108.65C134.25 107.74 130.98 105.43 126.93 106.07L126.94 106.08Z\" fill=\"#FF5718\"><\/path><path d=\"M72.9299 57.08V91.08C68.0999 92.71 62.9499 91.93 57.9299 92.09C59.7399 95.81 58.6999 100.08 58.9299 104.08H104.43C106.8 104.08 105.74 94.21 105.94 92.07C103.37 91.91 90.9299 93.2 90.9299 89.58V57.08H125.93V89.58C125.93 93.21 113.5 91.92 110.92 92.07C110.83 99.26 112.86 108.22 103.49 109.14C89.3199 110.53 72.3099 108.34 57.8699 108.64C52.5299 106.89 51.7099 96.6 53.9299 92.09C51.3599 91.9 38.9299 93.21 38.9299 89.58V57.08H72.9299Z\" fill=\"#FF5718\"><\/path><path d=\"M118.93 142.1C119.84 145.11 113.62 145.14 115.91 147.61C122.28 154.46 135.23 151.02 139.79 143.44C142.86 138.33 140.02 134.24 148.87 139.66C145.12 154.38 130.3 162.67 115.93 156.59C113.79 155.69 108.9 151.3 108.44 151.29C107.53 151.27 104.96 154.81 102.93 154.08L101.93 136.09L118.92 142.1H118.93Z\" fill=\"#FF5718\"><\/path><path d=\"M147.93 115.09L148.93 133.08C148.34 133.71 134.12 128.44 132.97 127.55C129.61 124.91 136.12 123.04 135.93 122.59C129.64 115.36 115.78 117.9 111.09 125.73C107.82 131.18 111.42 133.76 101.99 131.04C103.72 115.42 120.97 106.57 135.34 113.19C137.26 114.08 141.4 117.95 142.46 117.85C143.52 117.75 145.36 113.93 147.94 115.08L147.93 115.09Z\" fill=\"#FF5718\"><\/path><path d=\"M125.93 55.08H90.93C91.37 51.46 89.25 43.56 93.63 42.28C95.93 41.61 122.28 41.77 123.93 42.57C127.36 44.24 125.49 51.79 125.93 55.07V55.08Z\" fill=\"#FF5718\"><\/path><path d=\"M72.9301 55.08H38.9301C39.3701 52.31 37.8901 43.9 39.8701 42.52C41.1901 41.6 70.6801 41.6 72.0001 42.52C73.9801 43.9 72.4901 52.36 72.9401 55.08H72.9301Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2151_110\"><rect width=\"139.83\" height=\"152.6\" fill=\"white\" transform=\"translate(12 6)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0567983 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0567983\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arquiteturas resilientes com alta disponibilidade e Disaster Recovery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7344c3c e-con-full e-flex e-con e-child\" data-id=\"7344c3c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-950ca45 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"950ca45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308a060 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"308a060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2151_120)\"><path d=\"M125.46 141.32C123.21 139.04 112.24 128.34 111.52 126.74C110.16 123.74 112.02 121.24 111.46 119.7C111.3 119.27 105.44 113.4 105.02 113.21C104.21 112.84 94.39 118.81 92.28 119.53C67.26 128.11 38.15 113.32 34 86.76C46.17 84.1 44.87 93.11 51.03 100.23C70.13 122.31 108.07 110.93 111.92 82.17C117.52 40.3 59.58 24.4 43.97 65.22C43.32 66.91 42.24 73.38 41.91 73.66C41.1 74.35 33.91 73.38 32.01 73.75C34.68 41.81 67.77 21.44 97.22 36.04C118.9 46.79 127.75 72.46 118.49 94.73C117.58 96.93 112.95 104.01 113.16 105.1C113.27 105.67 118.41 111.01 119.05 111.29C120.92 112.11 122.47 110.57 124.71 111.45C127.55 112.56 150.72 134.93 153.01 138.24C159.13 147.08 151.48 158.03 140.98 155.27C136.15 154 129.23 145.12 125.46 141.3V141.32Z\" fill=\"#FF5718\"><\/path><path d=\"M110.01 15.77C106.3 25.06 96.76 17.36 90.28 15.99C87 15.3 83.31 15.74 80.02 14.76C81.82 25.88 72.2 25.87 74.01 14.76C63.53 15.18 42.62 21.99 35.99 30.25C34.15 32.54 38.67 33.89 39.55 35.79C42.41 42 32.86 41.46 30.52 35.79C15 54.37 10.59 78.57 20.15 101.12C21.45 104.19 27.69 116.17 30.65 116.69C32.59 117.03 36.59 109.08 39.55 114.77C41.56 118.62 34.23 121.11 35.48 122.77C46.79 131.92 59.3 137.8 74 138.76C72.6 127 81.4 126.96 80.02 138.76C90.29 137.52 99.55 135.38 108.52 130.04C115.95 135.15 112.41 136.34 105.99 139.25C54.82 162.44 -1.88997 117.82 9.47003 62.72C18.78 17.54 69.32 -4.97 110.01 15.77Z\" fill=\"#FF5718\"><\/path><path d=\"M21.5101 83.76C18.6701 82.9 19.4201 77.98 23.7301 76.98C28.8201 75.8 55.6501 77.74 56.9101 76.65C58.6601 72.43 62.1301 56.17 64.4801 53.73C68.0801 50 70.3401 54.95 71.3001 57.95C73.7801 65.64 75.0601 74.81 77.0101 82.75C82.1501 79.2 81.7001 67.43 84.9001 63.38C86.2501 61.68 89.7001 62.69 90.9201 64.34C92.6301 66.66 93.5201 74.76 96.0001 76.26C98.2001 77.59 102.74 76.27 105.48 76.78C110.38 77.69 109.36 83.75 107.51 83.75H91.0101C90.6301 83.75 89.2701 75.42 87.0201 77.75C86.1201 78.68 82.4301 95.11 80.3201 98.52C79.1901 100.35 75.8501 100.47 74.8901 99.15C71.3101 94.21 69.7001 75.4 66.9901 68.75L62.2101 81.46L60.5001 83.75H21.5101V83.76Z\" fill=\"#FF5718\"><\/path><path d=\"M126.02 82.76C126.29 81.57 126.84 76.08 127.09 75.84C127.34 75.6 131.66 75.35 134.06 74.3C158.6 63.64 149.88 20.47 117.74 26.98C113.2 27.9 107.41 34.12 105.3 34.65C104.39 34.88 100.2 32.95 100.04 32.72C97.5501 29.17 114.2 20.33 117.58 19.82C162.67 13.02 169.38 79.3 126.02 82.75V82.76Z\" fill=\"#FF5718\"><\/path><path d=\"M121.01 31.76C121.13 31.58 124.54 30.73 125.3 30.9C130.79 32.16 125.62 44.02 127 47.76C130.34 48.12 141.07 46 141.03 51.25C141.03 52.34 139.02 54.75 138.5 54.75H122.5C122.39 54.75 121 53.36 121 53.25C121 50.12 120.41 32.65 121 31.75L121.01 31.76Z\" fill=\"#FF5718\"><\/path><path d=\"M146.01 81.77C145.35 92.42 141.62 103.35 136.23 112.49C135.88 113.09 136.2 114.45 134.53 113.76C133.72 113.42 130.24 109.92 130.43 108.73C130.68 107.15 133.9 102.46 134.78 100.04C137.3 93.06 137.26 82.21 146.01 81.78V81.77Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2151_120\"><rect width=\"147.2\" height=\"147.72\" fill=\"white\" transform=\"translate(8 8)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5761806 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5761806\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Monitoramento cont\u00ednuo com atua\u00e7\u00e3o proativa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f393cfa e-con-full e-flex e-con e-child\" data-id=\"f393cfa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0f1295 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f0f1295\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">04<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd1a62 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4bd1a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2151_130)\"><path d=\"M115 32.85V57.35C115 58.25 108.7 62.92 107.32 63.67C88.29 74.09 28.69 74.84 11.65 60.69C10.65 59.86 8 57.41 8 56.34V31.84C11.56 34.2 14.99 36.73 19.02 38.32C38.71 46.07 79.41 46.04 99.51 39.86C105.19 38.12 109.7 35.24 114.99 32.84L115 32.85Z\" fill=\"#FF5718\"><\/path><path d=\"M125.24 87.61C125.84 88.31 131.34 89.98 132.48 89.87C134.83 89.63 136.92 85.53 139.36 86.01C139.88 86.11 146.63 92.57 147.07 93.32C149.73 97.84 144.18 99.24 144.47 102.95C144.51 103.47 146.03 108.4 146.22 108.63C147.33 109.98 153.21 109.66 154.51 111.84C155.28 113.14 155.36 121.7 154.86 123.22C153.93 125.98 148.13 124.93 146.51 126.87C146.1 127.36 144.11 132.59 144.21 133.19C144.54 135.19 148.59 137.46 147.9 140.16C147.75 140.76 140.7 148.06 139.98 148.42C137.41 149.69 134.24 145.47 132.26 145C131.9 144.92 125.49 146.81 125.21 147.05C124.13 147.96 124.62 154.32 123.08 155.43C122.12 156.12 112.04 156.2 110.64 155.73C108.13 154.88 109.97 149.94 106.37 147.01C99.8501 141.71 97.1701 149.37 93.6501 148.7C93.0901 148.59 85.7701 141.51 85.4701 140.84C83.8601 137.28 88.97 135.21 88.82 132.55C88.78 131.93 86.5101 126.74 86.0101 126.38C84.4401 125.23 79.6301 125.66 78.4801 123.91C77.7101 122.74 77.68 114.05 78.18 112.54C79.29 109.21 84.96 110.72 86.53 108.89C86.91 108.44 88.6501 103.05 88.6201 102.35C88.5201 100 84.36 97.57 85.14 94.58C85.33 93.86 91.25 87.74 92.02 87.39C97.12 85.01 97.5901 90.27 102.23 89.71C112 88.52 107.47 81.09 109.94 79.31C111.21 78.4 122.56 78.42 123.55 79.84C124.54 81.26 124 86.17 125.24 87.64V87.61ZM114.82 98.08C99.95 99.12 92.2401 115.7 100.16 128.19C107.53 139.8 124.58 140 132.44 128.79C142.15 114.93 131.54 96.91 114.82 98.09V98.08Z\" fill=\"#FF5718\"><\/path><path d=\"M54.79 8.15C69.25 7.45 98.7 9.09 110.49 17.86C117.03 22.73 116.3 26.74 109.93 31.29C92.21 43.95 28.34 44.08 11.52 29.82C0.740018 20.68 18.65 14.46 26 12.35C35.21 9.72 45.21 8.61 54.79 8.15Z\" fill=\"#FF5718\"><\/path><path d=\"M8 62.85L15.63 67.73C35.9 77.71 72.25 77.26 94.01 72.36C101.87 70.59 108.96 68.38 114.99 62.85L115.02 74.28C103.83 74.3 107.39 78.79 104.49 83.84C102.07 88.06 96.17 79.94 89.44 83.8C88.61 84.28 81.44 91.79 81.2 92.56C79.96 96.64 81.87 98.4 82.99 101.85C62.68 102.92 38.42 104.26 19.32 96.03C16.7 94.9 8 90.25 8 87.35L8 62.85Z\" fill=\"#FF5718\"><\/path><path d=\"M7.99999 93.85C26.89 108.36 53.28 106.63 75.99 106.86C75 109.92 73.53 112.05 73.37 115.52C73.3 117.11 73.83 123.83 74.2 125.15C75.52 129.88 83.92 128.35 84 132.35C84.04 134.03 54.27 134.08 51.45 133.9C41.57 133.29 20.92 129.94 13.05 124.3C12.22 123.71 7.98999 119.72 7.98999 119.36V93.86L7.99999 93.85Z\" fill=\"#FF5718\"><\/path><path d=\"M117.89 104.96C119.21 105.81 120.46 116.02 129 112.85C130.02 116.58 124.9 118 124.16 120.57C123.36 123.38 125.4 126.05 124.99 128.84C121.85 130.05 119.41 126.26 117.35 126.05C114.99 125.81 111.23 130.04 108 128.84C107.59 126.05 109.64 123.38 108.83 120.57C108.09 118 102.97 116.58 103.99 112.85C106.24 112.71 108.88 113.37 110.99 112.35C113.99 110.91 114.18 102.58 117.87 104.96H117.89Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2151_130\"><rect width=\"147.18\" height=\"148.02\" fill=\"white\" transform=\"translate(8 8)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b50bb7 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3b50bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Especialistas em ambientes cr\u00edticos e banco de dados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd74146 e-flex e-con-boxed e-con e-parent\" data-id=\"bd74146\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4cdb5b e-con-full e-flex e-con e-child\" data-id=\"a4cdb5b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_effects_offset&quot;:90,&quot;sticky_anchor_link_offset&quot;:90}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-578e564 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"578e564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A nuvem deveria simplificar sua opera\u00e7\u00e3o \u2014 mas muitas empresas est\u00e3o enfrentando o oposto<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fef389c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fef389c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"13\">A promessa da cloud \u00e9 clara:<br \/><strong>escalabilidade, efici\u00eancia e redu\u00e7\u00e3o de custos. <\/strong><\/p><p data-path-to-node=\"13\">Mas sem estrat\u00e9gia, o cen\u00e1rio se torna complexo, caro e arriscado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea9dcd3 elementor-widget elementor-widget-video\" data-id=\"ea9dcd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/06\/magnific_subtle-elegant-hightech-animation-the-volumetric-c_kling_1080p_1-1_24fps_52321-1.mp4\" autoplay=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2d15c8 e-con-full e-flex e-con e-child\" data-id=\"f2d15c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-89f28a6 e-con-full e-flex e-con e-child\" data-id=\"89f28a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-790d85b e-con-full e-flex e-con e-child\" data-id=\"790d85b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58054d2 elementor-widget elementor-widget-image\" data-id=\"58054d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-60-1.svg\" class=\"attachment-large size-large wp-image-1284\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-791d0f4 e-con-full e-flex e-con e-child\" data-id=\"791d0f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5bafd0 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"a5bafd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Custos fora de controle<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1a835 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a1a835\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ece0e2a elementor-widget elementor-widget-text-editor\" data-id=\"ece0e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ambientes mal configurados geram desperd\u00edcio constante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-944c1ec e-con-full e-flex e-con e-child\" data-id=\"944c1ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-79ada42 e-con-full e-flex e-con e-child\" data-id=\"79ada42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6e5946 elementor-widget elementor-widget-image\" data-id=\"b6e5946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-61-1.svg\" class=\"attachment-large size-large wp-image-1285\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3ca9f3 e-con-full e-flex e-con e-child\" data-id=\"c3ca9f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eef8658 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"eef8658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Risco de indisponibilidade<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3016a9f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3016a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e95b64 elementor-widget elementor-widget-text-editor\" data-id=\"1e95b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Arquiteturas fr\u00e1geis impactam diretamente o neg\u00f3cio<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbcf51c e-con-full e-flex e-con e-child\" data-id=\"cbcf51c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-1d7eb2d e-con-full e-flex e-con e-child\" data-id=\"1d7eb2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab6b51 elementor-widget elementor-widget-image\" data-id=\"7ab6b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-62-1.svg\" class=\"attachment-large size-large wp-image-1286\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0663f8 e-con-full e-flex e-con e-child\" data-id=\"a0663f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fba1abd elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"fba1abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Depend\u00eancia de fornecedor (lock-in)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5485b01 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5485b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe9ee5 elementor-widget elementor-widget-text-editor\" data-id=\"7fe9ee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Falta de flexibilidade e aumento de risco estrat\u00e9gico<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5faacd5 e-con-full e-flex e-con e-child\" data-id=\"5faacd5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-8fa7500 e-con-full e-flex e-con e-child\" data-id=\"8fa7500\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b19e1e elementor-widget elementor-widget-image\" data-id=\"3b19e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-63.svg\" class=\"attachment-large size-large wp-image-1287\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-082438b e-con-full e-flex e-con e-child\" data-id=\"082438b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-897128a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"897128a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Falta de visibilidade e controle<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d77241 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6d77241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a774d2 elementor-widget elementor-widget-text-editor\" data-id=\"8a774d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sem governan\u00e7a, n\u00e3o h\u00e1 controle sobre custos e performance<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-166759d e-flex e-con-boxed e-con e-parent\" data-id=\"166759d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0e8da26 e-con-full e-flex e-con e-child\" data-id=\"0e8da26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4944159 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"4944159\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Antes de qualquer migra\u00e7\u00e3o, entendemos o seu neg\u00f3cio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c436c17 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c436c17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee0f348 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"ee0f348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Na WiseDB, n\u00e3o come\u00e7amos pela tecnologia<br> \u2014 come\u00e7amos pelo diagn\u00f3stico.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c0eda5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8c0eda5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Realizamos uma an\u00e1lise completa da sua infraestrutura para identificar:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1ff87 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f1ff87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gargalos de performance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Riscos operacionais<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desperd\u00edcios financeiros<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Limita\u00e7\u00f5es de escalabilidade<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6456c3f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6456c3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Toda decis\u00e3o \u00e9 baseada em dados reais, n\u00e3o em suposi\u00e7\u00f5es.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-731fe17 e-con-full e-flex e-con e-child\" data-id=\"731fe17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea6ddac elementor-widget elementor-widget-image\" data-id=\"ea6ddac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"508\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-65.jpg\" class=\"attachment-large size-large wp-image-1302\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-65.jpg 699w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-65-300x218.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f14981 e-flex e-con-boxed e-con e-parent\" data-id=\"9f14981\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9351562 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9351562\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">nossa solu\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3469dd elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"e3469dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Uma estrat\u00e9gia completa de Cloud, do diagn\u00f3stico \u00e0 opera\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7314d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6b7314d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Desenhamos, implementamos e operamos ambientes cloud modernos, seguros e preparados para crescimento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfa4502 e-grid e-con-boxed e-con e-parent\" data-id=\"dfa4502\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-71489ed e-con-full e-flex e-con e-child\" data-id=\"71489ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c87c2a9 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c87c2a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9567f73 elementor-widget elementor-widget-image\" data-id=\"9567f73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"274\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-66.jpg\" class=\"attachment-large size-large wp-image-1306\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-66.jpg 410w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-66-300x200.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a19ca29 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"a19ca29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An\u00e1lise Consultiva (Assessment)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00385fb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"00385fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66a880d elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"66a880d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Mapeamos sua infraestrutura atual para expor onde h\u00e1 desperd\u00edcio, risco e gargalo de performance. Voc\u00ea decide a migra\u00e7\u00e3o sabendo exatamente o que mudar e por qu\u00ea, sem mover nada no escuro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96a0ea5 e-con-full e-flex e-con e-child\" data-id=\"96a0ea5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb120c8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fb120c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d0c96 elementor-widget elementor-widget-image\" data-id=\"31d0c96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"274\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-67.jpg\" class=\"attachment-large size-large wp-image-1307\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-67.jpg 410w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-67-300x200.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b81108a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"b81108a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arquitetura Multicloud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e81182b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e81182b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c87d1c0 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c87d1c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Combinamos Oracle Cloud, AWS e Azure conforme o que cada carga de trabalho exige. O resultado \u00e9 independ\u00eancia de fornecedor, melhor custo por workload e uma arquitetura que acompanha o crescimento sem travar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c03106a e-con-full e-flex e-con e-child\" data-id=\"c03106a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9cda72 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e9cda72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa0092f elementor-widget elementor-widget-image\" data-id=\"aa0092f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"274\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-68.jpg\" class=\"attachment-large size-large wp-image-1308\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-68.jpg 410w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-68-300x200.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f32beb elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"8f32beb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Migra\u00e7\u00e3o para a Nuvem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd7d394 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd7d394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08cb2b4 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"08cb2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Executamos a migra\u00e7\u00e3o com testes e valida\u00e7\u00f5es em cada etapa, sem interromper sua opera\u00e7\u00e3o. Sistemas cr\u00edticos saem do ambiente atual e entram em produ\u00e7\u00e3o na nuvem sem parada e sem perda de dado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6003952 e-con-full e-flex e-con e-child\" data-id=\"6003952\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e1b2d animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d2e1b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ebeb9 elementor-widget elementor-widget-image\" data-id=\"27ebeb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"274\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-69.jpg\" class=\"attachment-large size-large wp-image-1309\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-69.jpg 410w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-69-300x200.jpg 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c63eb04 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"c63eb04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Otimiza\u00e7\u00e3o de Custos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4be252e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4be252e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4bd635 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e4bd635\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Eliminamos o que voc\u00ea paga e n\u00e3o usa e instalamos a governan\u00e7a para que o gasto n\u00e3o volte a escapar. Empresas que passam por essa etapa reduzem de 30% a 40% o custo de cloud, com visibilidade total sobre cada recurso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cf8c17 e-flex e-con-boxed e-con e-parent\" data-id=\"0cf8c17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f821b6 e-con-full e-flex e-con e-child\" data-id=\"1f821b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-04e7961 e-con-full e-grid e-con e-child\" data-id=\"04e7961\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9f590a elementor-widget elementor-widget-counter\" data-id=\"a9f590a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0adc67 elementor-widget elementor-widget-heading\" data-id=\"d0adc67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">projetos de migra\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-288961f e-con-full e-grid e-con e-child\" data-id=\"288961f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b69e25 elementor-widget elementor-widget-counter\" data-id=\"5b69e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"95\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a7a13 elementor-widget elementor-widget-heading\" data-id=\"60a7a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NPS <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93086ee e-con-full e-grid e-con e-child\" data-id=\"93086ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a30040 elementor-widget elementor-widget-counter\" data-id=\"2a30040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"16\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f53852b elementor-widget elementor-widget-heading\" data-id=\"f53852b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anos de Experi\u00eancia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc82c86 e-flex e-con-boxed e-con e-parent\" data-id=\"dc82c86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49090a5 elementor-widget elementor-widget-heading\" data-id=\"49090a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trabalhamos com os principais cloud providers do mercado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86c59be elementor-widget elementor-widget-image\" data-id=\"86c59be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"8\" height=\"45\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/arrow2.svg\" class=\"attachment-large size-large wp-image-166\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da68913 e-con-full e-flex e-con e-parent\" data-id=\"da68913\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e5880 elementor-widget elementor-widget-image-carousel\" data-id=\"11e5880\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:300,&quot;speed&quot;:3200,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:67,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/oNLYyT.tif.svg\" alt=\"oNLYyT.tif\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/07\/oracle.svg\" alt=\"oracle\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/07\/azure.svg\" alt=\"azure\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1e02da e-flex e-con-boxed e-con e-parent\" data-id=\"b1e02da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f92684 e-con-full e-flex e-con e-child\" data-id=\"1f92684\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31394f7 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"31394f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Multicloud: uma estrat\u00e9gia global para empresas que precisam de flexibilidade e controle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1595f42 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1595f42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-709d130 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"709d130\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A ado\u00e7\u00e3o de m\u00faltiplos provedores de nuvem \u00e9 hoje uma tend\u00eancia global \u2014 e uma necessidade para empresas que operam ambientes cr\u00edticos.<\/p><p>Multicloud n\u00e3o \u00e9 usar v\u00e1rias nuvens.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aed7db2 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"aed7db2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9 usar a nuvem certa para cada necessidade.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6488ac2 e-con-full e-flex e-con e-child\" data-id=\"6488ac2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67bd5b0 elementor-widget elementor-widget-image\" data-id=\"67bd5b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"699\" height=\"508\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-70.jpg\" class=\"attachment-large size-large wp-image-1313\" alt=\"\" srcset=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-70.jpg 699w, https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-70-300x218.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ea412d e-flex e-con-boxed e-con e-parent\" data-id=\"5ea412d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0db33a3 e-con-full e-flex e-con e-child\" data-id=\"0db33a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d11bbdc elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"d11bbdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vantagens da Arquitetura Multicloud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-665e4ef e-grid e-con-boxed e-con e-parent\" data-id=\"665e4ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e77ae5e e-con-full e-flex e-con e-child\" data-id=\"e77ae5e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05d49bd elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"05d49bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"141\" height=\"82\" viewBox=\"0 0 141 82\" fill=\"none\"><g clip-path=\"url(#clip0_2152_333)\"><path d=\"M2.25192 35.5527L44.3672 35.837C45.1379 36.1923 45.433 36.4875 45.5915 37.3457C45.8758 38.9036 45.8484 51.8751 45.4877 53.0941C45.1269 54.3131 43.2685 55.1002 42.0551 55.1276C30.0081 54.3404 16.7477 56.1388 4.85372 55.1385C3.52549 55.0292 1.62333 54.8816 0.819835 53.7063C0.0163385 52.5311 -0.131243 38.5592 0.513741 37.0888C0.737846 36.5804 1.70532 35.7113 2.25738 35.5527H2.25192Z\" fill=\"#FF5718\"><\/path><path d=\"M2.79861 19.7004H43.0117C44.2361 20.094 45.3183 20.6953 45.5752 22.0564C45.7884 23.1606 45.7829 30.9446 45.4987 31.7919C45.3129 32.3549 44.8647 32.6118 44.3673 32.8469C30.4455 33.6996 16.2613 33.1475 2.25201 33.1311C-0.502833 32.344 -0.0764875 25.5986 0.213209 23.1278C0.420915 21.3513 0.95658 20.1596 2.79861 19.7004Z\" fill=\"#FF5718\"><\/path><path d=\"M131.954 44.1842C131.872 44.3208 129.45 45.2337 128.975 45.3048L89.7128 45.1572C88.4885 44.7636 87.4062 44.1623 87.1493 42.8012C86.8432 41.205 86.6902 31.6062 88.5049 31.6062H130.593C130.691 31.6062 131.959 32.8744 131.959 32.9728C131.959 34.6181 132.254 43.7031 131.959 44.1787L131.954 44.1842Z\" fill=\"#FF5718\"><\/path><path d=\"M130.587 47.4639C132.331 47.9558 132.604 52.9684 131.948 54.5755C130.631 53.3511 128.691 54.6685 127.898 54.4881C127.034 54.2967 126.865 51.826 125.127 52.389C123.831 53.0395 124.635 54.8652 124.208 55.5704C124.088 55.7672 121.115 57.0955 120.202 57.8498C119.53 58.4074 118.19 60.583 118.016 60.583H88.4993C87.5209 60.583 87.182 58.4183 87.1 57.6093C86.9361 55.964 86.6628 47.4639 88.4993 47.4639H130.587Z\" fill=\"#FF5718\"><\/path><path d=\"M106.319 16.8088L111.719 14.1194C112.134 14.6825 111.418 26.2983 111.183 28.0694C111.096 28.7473 111.435 29.0971 110.352 28.8894C107.319 28.299 102.022 23.1771 98.6115 22.3079L98.9504 21.1819C99.5408 20.3947 103.372 19.7716 102.973 18.7767C101.973 16.295 93.796 11.0364 91.1505 9.82838C73.5993 1.79838 45.8267 2.15369 29.56 13.1191C27.6415 14.4146 26.4663 17.3828 23.7278 16.0326C19.7158 14.0538 29.079 8.24862 30.8226 7.27562C49.1828 -2.97917 80.306 -2.31775 98.2289 8.75698C101.47 10.7631 104.722 13.2066 106.319 16.8088Z\" fill=\"#FF5718\"><\/path><path d=\"M89.046 76.4353C88.7727 76.3807 87.5593 75.5935 87.4063 75.3421C86.7394 74.2379 86.7831 64.2072 87.9911 63.3545C90.7296 61.4249 111.888 63.595 116.649 62.7696C116.425 65.1201 115.851 67.1153 116.152 69.5533C116.469 72.1388 118.163 74.063 118.836 76.4299H89.046V76.4353Z\" fill=\"#FF5718\"><\/path><path d=\"M126.887 56.3412C138.737 54.1054 145.832 68.8371 137.136 76.4298C128.04 84.3778 114.26 74.5986 118.945 63.1576C120.186 60.1238 123.64 56.9534 126.887 56.3412ZM129.057 71.8928L136.31 64.1361C135.337 63.174 135.206 62.3596 133.845 63.2779C132.768 64.0049 128.406 69.7227 127.794 69.8539C127.182 69.9851 122.935 65.0326 122.667 67.9571C122.629 68.3834 126.575 73.9481 129.051 71.8873L129.057 71.8928Z\" fill=\"#FF5718\"><\/path><path d=\"M20.9949 72.0623V58.1232C20.9949 58.0576 21.771 57.0573 22.1099 57.5383C24.433 59.7358 31.8776 61.9824 33.583 64.1252C34.8292 65.694 30.2269 66.2461 29.7568 67.4159C41.2189 79.2778 61.5195 80.1415 76.0262 73.7951C78.1033 72.8877 81.4976 69.6626 83.3342 71.2041C86.2366 73.6311 80.9292 76.1128 78.8685 77.1897C65.3129 84.2576 44.7609 83.536 31.976 75.025C30.5876 74.1012 26.0728 69.433 25.6464 69.4275C25.1107 69.4275 22.1755 72.2372 20.9949 72.0623Z\" fill=\"#FF5718\"><\/path><path d=\"M59.6883 41.3472C60.0218 40.7678 59.743 38.7671 60.0382 37.5919C61.197 33.0002 65.9742 31.0378 69.9097 33.7982C73.55 36.351 71.5331 39.0623 72.6372 40.9099C73.0472 41.5932 74.6214 41.6971 74.9985 42.9215C75.3429 44.0476 75.2718 49.6013 75.1078 51.028C74.8947 52.8866 74.6432 53.8268 72.67 54.0564C70.6968 54.2859 59.262 54.2313 58.3765 53.5316C57.1959 52.6023 57.2505 43.3697 58.1196 42.2164C58.4694 41.7517 59.5244 41.626 59.6883 41.3472ZM69.6419 41.4565C71.074 33.2407 61.6452 33.2516 63.0772 41.4565H69.6419Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_333\"><rect width=\"141\" height=\"82\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fcca22 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"4fcca22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Independ\u00eancia tecnol\u00f3gica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd7a8b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1bd7a8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3834aaf e-con-full e-flex e-con e-child\" data-id=\"3834aaf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d80649b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d80649b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"143\" height=\"104\" viewBox=\"0 0 143 104\" fill=\"none\"><g clip-path=\"url(#clip0_2152_325)\"><path d=\"M78.6417 49.9171C79.1903 50.2411 83.4097 48.4823 86.5064 50.4983C90.1106 52.8434 89.2134 55.5435 90.6233 57.6829C91.095 58.3927 93.2175 59.0047 94.1916 59.7607C102.292 66.0453 98.5649 78.2803 88.5469 79.2986C80.3849 80.1266 63.4609 80.034 55.2117 79.3243C43.1327 78.2803 39.9181 63.9624 50.1668 58.7938C51.0691 58.3412 53.7608 57.7909 53.8838 57.6366C54.1043 57.3692 54.7656 52.7149 55.7141 50.9869C60.2361 42.7839 71.3615 42.1256 77.8214 48.4308C78.2367 48.8371 78.4879 49.8246 78.6417 49.9171Z\" fill=\"#FF5718\"><\/path><path d=\"M136.586 31.8912C136.73 32.1226 139.832 33.1923 141.103 34.8175C144.461 39.1015 143.328 46.1268 138.001 48.1582C134.295 49.5725 116.381 49.3308 111.608 48.9811C109.885 48.8525 105.276 47.3971 104.574 47.4999C102.502 47.8085 92.4794 55.0549 91.8949 54.6177C91.9821 53.6354 90.5106 52.4423 91.0797 51.532C92.1769 49.7782 101.011 46.3119 101.908 44.841C102.318 44.1673 101.072 41.3644 101.098 39.9861C101.149 37.4609 102.897 34.4421 105.04 33.1049C106.317 32.3077 108.629 32.0969 108.762 31.9529C108.886 31.8243 108.814 30.1014 109.024 29.3917C111.064 22.5465 118.514 18.715 124.866 22.8139C125.845 23.4465 127.419 25.5757 128.086 25.6991C129.101 25.8842 130.454 24.9071 132.413 25.5345C133.285 25.8174 135.504 27.9054 135.909 28.7077C136.525 29.9214 136.299 31.4489 136.576 31.8963L136.586 31.8912Z\" fill=\"#FF5718\"><\/path><path d=\"M111.546 79.4735C115.099 75.8941 120.585 74.9632 124.871 77.8381C125.804 78.4655 127.25 80.3684 127.752 80.5587C129.024 81.0318 131.418 79.4118 134.11 81.4278C136.576 83.2741 136.186 86.4885 136.561 86.941C136.663 87.0696 138.478 87.4348 139.58 88.2833C145.369 92.732 143.384 102.617 136.248 103.476C130.531 104.165 113.741 104.165 108.024 103.476C101.144 102.647 98.8008 92.4902 104.451 88.5508C104.83 87.3679 109.321 87.2856 108.803 86.2365C108.393 85.4136 98.9136 80.1678 97.1499 78.9078C96.868 78.7072 96.1707 78.913 96.5193 78.0232C96.8321 77.2261 98.2522 76.1203 99.2058 76.2643C101.077 76.5472 107.045 81.2427 109.147 82.3227C110.259 82.4821 110.793 80.2244 111.546 79.4632V79.4735Z\" fill=\"#FF5718\"><\/path><path d=\"M56.7652 27.3552C50.4591 26.3061 48.1264 17.2134 52.9713 12.7493C54.0736 11.731 57.8214 10.543 57.9649 10.3013C58.2623 9.7973 57.9342 8.29042 58.2879 7.28241C60.3592 1.37835 67.0498 -1.64568 72.8638 0.925773C74.4121 1.60978 76.6731 4.48981 77.3344 4.6081C78.9238 4.90125 80.3696 3.46637 83.1278 5.02982C85.8861 6.59326 85.3119 9.27272 86.3988 10.7539C87.0141 11.5973 89.8851 12.6619 91.0951 14.5288C93.474 18.1854 92.5152 23.2254 89.0699 25.8175C88.6906 26.1055 86.6552 27.3603 86.5065 27.3603H72.9202V42.7891C71.9204 42.7737 69.7312 42.4188 69.3928 41.4314C69.5261 37.533 70.3259 33.0176 69.8696 29.1347C69.8081 28.6152 69.6338 27.3603 69.075 27.3603C65.6194 27.3603 59.867 27.8746 56.7704 27.3603L56.7652 27.3552ZM67.6497 8.43957C66.896 8.60414 66.2449 9.01558 65.7527 9.61215C65.7271 11.1447 76.1399 11.4893 77.5241 9.61215C77.5087 8.04357 69.0134 8.13614 67.6497 8.43957ZM77.5293 11.4122C73.6636 12.6105 69.5877 13.0836 65.7476 11.4122C64.0916 14.7911 69.7927 15.0328 72.0691 14.9711C74.5915 14.9042 78.7136 14.6522 77.5344 11.4122H77.5293ZM65.8348 18.0002C66.4705 18.782 79.8723 20.1397 77.5293 15.0122C73.5405 17.3008 69.4749 16.2259 65.2298 15.5316C65.7527 16.1694 65.5682 17.6762 65.8348 18.0002ZM77.4421 21.6106C77.7805 21.0449 77.4318 19.8466 77.5241 19.1265C75.6067 21.3637 66.1526 19.214 65.7373 19.6408C65.5938 19.79 65.7015 21.2917 65.9732 21.7134C66.9627 23.2512 76.55 23.0866 77.437 21.6106H77.4421Z\" fill=\"#FF5718\"><\/path><path d=\"M45.1323 76.3105C45.2605 76.3877 47.0959 78.378 46.7678 78.774C45.3579 79.5763 35.6527 84.678 35.4835 85.3106C34.8785 87.5272 36.8524 87.1364 38.2315 88.1238C44.4761 92.5827 41.9383 102.745 34.2376 103.496C28.3417 104.067 12.2227 104.226 6.57279 103.424C-1.26114 102.313 -2.46597 90.6284 5.24492 87.2495C5.83964 86.9872 7.03934 87.1415 7.23416 86.9512C7.3367 86.8535 7.51102 84.8838 7.77762 84.1535C10.1719 77.6425 16.2011 73.9653 22.8354 77.334C24.0863 77.9665 25.8961 80.0083 26.619 80.2243C27.9367 80.6151 29.5824 80.1111 31.0231 80.4351C32.2638 80.7128 33.2379 82.1992 33.6839 82.2403C35.2528 82.374 43.4712 75.3231 45.1272 76.3105H45.1323ZM17.4162 84.5649C16.5549 84.7192 15.5654 85.0072 14.9912 85.722C14.9861 87.2495 25.0399 87.7895 26.2499 85.722C26.2345 84.03 18.7543 84.3232 17.4162 84.5649ZM26.7677 87.5272C22.902 88.7615 18.8312 89.0238 14.9861 87.5272C15.0886 88.2164 14.7964 89.1987 14.9502 89.7849C15.2834 91.0347 28.1571 92.5776 26.7677 87.5272ZM26.7728 91.6415C26.6549 91.5027 25.0502 92.1147 24.4709 92.1558C22.5636 92.2947 20.236 92.233 18.2878 92.1815C16.3396 92.1301 14.5041 90.7775 14.9707 92.9324C15.5551 95.617 25.6398 95.113 26.537 93.7141C26.8036 93.2976 26.9215 91.8164 26.7728 91.6415ZM26.7677 95.2416C23.4096 96.697 18.298 96.9593 14.9861 95.2416C13.7505 99.6182 20.9487 99.145 23.8146 98.7028C26.3319 98.3119 27.142 98.101 26.7677 95.2416Z\" fill=\"#FF5718\"><\/path><path d=\"M26.337 25.766C26.6549 26.0026 30.618 24.0174 33.7198 27.3294C35.2527 28.9649 35.0528 31.0118 35.7552 31.9735C36.0987 32.4466 38.5186 33.2901 39.4107 34.2158C42.0613 36.9724 42.3689 41.5136 40.6155 44.8256L52.8842 51.568L51.905 54.88C51.0231 55.5589 39.5132 46.9805 38.3135 47.0525C37.8829 47.0782 37.0728 48.1222 36.1448 48.3228C35.0169 48.5697 32.8277 48.8474 31.6383 48.94C26.7728 49.3102 9.06958 49.5931 5.23464 48.1788C-0.46136 46.0754 -1.83025 37.6975 2.70707 33.8044C4.03495 32.6626 6.92653 32.1175 7.18287 31.8655C7.38795 31.6649 7.96217 28.6357 8.3877 27.674C11.428 20.7774 18.9543 19.3322 24.9066 23.822C25.8756 24.5523 26.1832 25.6426 26.337 25.7557V25.766ZM27.7982 33.5266C27.8854 32.8015 27.9366 29.9266 27.0292 29.9266H13.9555V33.5266H27.7982ZM27.7982 38.6696C27.8854 37.9444 27.9366 35.0695 27.0292 35.0695H13.9555V38.6696H27.7982ZM27.7982 40.2124H13.9555V43.8125H27.7982V40.2124Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_325\"><rect width=\"143\" height=\"104\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b18cb8 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"1b18cb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Otimiza\u00e7\u00e3o de custos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b63dad9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b63dad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-466c268 e-con-full e-flex e-con e-child\" data-id=\"466c268\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5468aae elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5468aae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"134\" height=\"126\" viewBox=\"0 0 134 126\" fill=\"none\"><g clip-path=\"url(#clip0_2152_307)\"><path d=\"M99.2136 84.8442C105.524 90.3028 117.331 102.152 122.739 108.516C125.238 111.448 126.969 114.049 124.948 117.967C124.632 118.589 118.563 124.858 117.998 125.182C115.519 126.608 112.131 126.034 109.875 124.473C106.164 121.899 87.1242 102.666 84.2686 98.8149C81.4129 94.9642 83.5951 93.2347 82.9081 91.3364C82.7801 90.9784 77.8299 86.1413 77.4123 86.04C76.0721 85.6954 73.2434 88.5868 71.6 89.4651C13.7327 120.338 -28.4353 36.6763 23.5591 6.80271C69.0609 -19.335 116.24 35.3792 85.4135 76.8455C85.4135 77.2711 90.9295 82.7499 91.3269 82.8918C93.3407 83.6214 95.2601 81.4191 99.2136 84.8442ZM42.7202 10.4913C-6.53297 16.4633 3.96693 95.579 55.6986 84.9861C100.756 75.7578 90.4513 4.69494 42.7202 10.4913Z\" fill=\"#FF5718\"><\/path><path d=\"M107.861 1.52002C111.081 2.10776 110.71 13.2884 110.198 16.0244C109.754 18.3957 107.949 18.9226 105.881 19.1253C103.356 19.3685 90.3435 19.4293 88.68 18.7335C87.7909 18.3551 82.3895 11.5387 80.5912 9.95785C76.8331 6.64757 72.2869 4.65465 68.4614 1.52002H107.861Z\" fill=\"#FF5718\"><\/path><path d=\"M113.337 15.7947C114.502 15.3894 128.861 15.4164 130.788 15.6731C132.99 15.9636 133.522 16.477 133.818 18.7132C134.014 20.1927 133.973 29.1642 133.475 29.9141C132.37 31.5895 114.772 31.8057 113.539 30.9477C112.408 30.1573 113.081 26.0633 112.758 24.3069C112.482 22.7936 110.98 21.1182 111.027 20.2197C111.061 19.5779 112.616 16.0514 113.337 15.8015V15.7947Z\" fill=\"#FF5718\"><\/path><path d=\"M120.995 73.8057C119.136 73.495 113.532 74.5286 112.522 73.1504C112.104 72.5762 113.714 59.7472 112.913 58.9365C112.569 58.592 106.817 59.4634 106.838 58.5987C109.943 53.9103 112.69 48.7287 116.078 44.2564C116.408 43.8241 115.984 43.0945 117.27 43.3985C118.981 47.7491 125.804 53.9441 127.036 57.9434C127.642 59.9093 121.897 58.5649 120.981 58.9433V73.8057H120.995Z\" fill=\"#FF5718\"><\/path><path d=\"M107.861 42.0541C108.218 42.1554 109.909 43.9997 110.077 44.5537C111.694 49.9244 104.366 56.268 102.137 60.9632H110.219V67.0501H94.0547C97.0248 59.1797 98.749 50.4311 97.4222 42.0541C100.258 42.554 105.39 41.3718 107.861 42.0541Z\" fill=\"#FF5718\"><\/path><path d=\"M96.7485 39.3519C96.8967 35.7241 94.7819 33.319 96.0414 29.6372C92.4987 28.2928 92.3842 24.9893 90.687 21.7871H107.861C110.953 21.7871 110.771 35.3255 109.868 37.3116C109.707 37.6629 108.003 39.3519 107.861 39.3519H96.7485Z\" fill=\"#FF5718\"><\/path><path d=\"M120.496 42.8716C120.564 42.7364 121.587 42.75 121.688 42.3243C122.725 37.7508 118.011 40.9259 116.287 38.6763L115.512 40.9394L112.913 43.7498C108.925 40.2098 113.99 37.8724 112.913 33.265C116.435 33.8527 131.899 31.9544 133.468 34.6094C134.283 36.001 134.343 47.5465 132.451 48.472C131.205 49.08 124.935 49.08 123.689 48.472C122.847 48.0599 120.052 43.743 120.503 42.8716H120.496Z\" fill=\"#FF5718\"><\/path><path d=\"M123.682 67.0501V60.9632H131.764L125.702 51.5188C129.036 51.8093 133.232 50.0123 133.818 54.5183C134.02 56.0856 133.993 64.7937 133.461 65.7057C132.202 67.8405 125.952 66.8272 123.682 67.0501Z\" fill=\"#FF5718\"><\/path><path d=\"M67.6332 72.9612C66.8182 73.7179 65.1951 73.7381 64.1107 73.826C57.5306 74.3799 45.7174 74.3732 39.1305 73.826C36.4904 73.603 34.1938 73.272 35.2781 69.9617C38.4032 66.6109 47.6436 46.3912 50.2635 45.0671C50.9977 44.6955 51.7183 44.5536 52.5198 44.8171C54.089 45.3373 65.9292 67.4959 67.9497 70.6305C68.3403 71.3331 68.1787 72.4478 67.6264 72.9612H67.6332Z\" fill=\"#FF5718\"><\/path><path d=\"M32.9276 23.2937C34.9077 21.294 61.3629 22.9829 65.9763 22.5911C68.832 23.4626 68.6704 33.3664 67.1213 34.2919C64.0838 36.1159 39.2922 33.6974 33.9109 34.4811C31.0148 33.7582 31.7961 24.4354 32.9276 23.2937Z\" fill=\"#FF5718\"><\/path><path d=\"M65.7675 36.6494C66.6296 37.4263 58.8035 47.3572 58.0222 48.7961C56.8503 48.8164 56.1566 41.9931 51.3882 42.2566C46.6198 42.5201 46.3302 48.1543 45.4547 48.7015C44.5791 49.2487 33.6616 49.0866 32.6985 47.8638C31.4458 46.2762 31.3919 36.6494 34.4496 36.6494H65.7675Z\" fill=\"#FF5718\"><\/path><path d=\"M66.4411 48.8097C66.0707 48.4381 61.9286 49.3569 61.0598 48.4786C62.9928 46.9451 69.2631 34.9065 70.8121 35.3051C71.5597 35.4942 79.6215 47.0937 79.9044 47.8166C80.6318 49.6947 75.4526 48.5124 74.5231 48.8164V63.0033H66.4411C66.0639 61.0374 66.9395 49.3163 66.4411 48.8164V48.8097Z\" fill=\"#FF5718\"><\/path><path d=\"M30.072 30.5693C31.0014 34.6768 31.2573 36.6089 30.072 40.7028H18.2857C16.6962 40.7028 16.6356 30.5693 18.9592 30.5693H30.072Z\" fill=\"#FF5718\"><\/path><path d=\"M18.959 52.1877C16.6421 51.5391 16.4468 43.4458 18.6222 42.3919C21.0266 41.2164 27.142 42.5541 30.0785 42.0541C28.9672 44.02 33.015 52.1877 29.7417 52.1877C27.2633 52.1877 20.7572 52.6876 18.9657 52.1877H18.959Z\" fill=\"#FF5718\"><\/path><path d=\"M30.072 53.5386C30.0989 56.7205 29.7554 59.9362 30.7455 62.9965H18.2857C16.7703 62.9965 16.7703 53.5386 18.2857 53.5386H30.072Z\" fill=\"#FF5718\"><\/path><path d=\"M43.542 50.8364L36.8744 62.5575C29.8699 66.4015 31.6951 50.8364 33.7763 50.8364H43.542Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_307\"><rect width=\"134\" height=\"126\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdf5c43 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"cdf5c43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Melhor performance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd92182 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd92182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b811363 e-con-full e-flex e-con e-child\" data-id=\"b811363\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be052f4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"be052f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"140\" height=\"149\" viewBox=\"0 0 140 149\" fill=\"none\"><g clip-path=\"url(#clip0_2152_344)\"><path d=\"M0.307236 61.2665L14.5287 55.8608C16.8197 57.3141 27.9538 60.1994 28.9107 61.4561C29.8677 62.7127 29.735 68.7011 29.5394 70.6387C28.6942 79.0561 19.7395 93.1249 10.4494 87.7332C1.1594 82.3416 -0.810361 71.6707 0.307236 61.2665Z\" fill=\"#FF5718\"><\/path><path d=\"M73.461 0.182575C73.929 0.512532 73.7614 3.03986 75.3749 4.24736C77.5193 5.85502 81.0746 1.09522 83.708 6.43069C84.5741 8.18578 81.9897 9.31605 82.2272 10.664C82.8907 14.3988 88.6603 11.7381 87.5497 17.9862C87.0328 20.9067 81.8639 19.1024 82.6183 23.5604C83.0025 25.842 85.4333 25.6384 82.6532 28.5588C79.6148 31.7531 78.3156 27.934 75.3889 28.952C73.3283 29.6681 75.0326 34.6876 69.738 33.789C66.0569 33.1642 68.8719 28.4746 64.157 28.8888C61.9987 29.0784 61.377 31.388 58.8624 28.5378C56.0265 25.3154 59.7215 24.4168 58.4223 21.3279C57.4444 19.0112 53.8472 21.2998 53.9519 16.6102C54.0707 11.4573 57.2558 14.3567 58.2547 13.0228C60.3921 10.1655 55.3559 7.0906 59.1767 4.25438C61.7332 2.35186 63.1651 5.28637 65.1768 4.73176C67.8591 3.99463 67.433 0.610817 68.0407 0.182575C68.3829 -0.0631371 73.0978 -0.0631371 73.447 0.182575H73.461ZM74.7532 21.6508C81.6544 15.8941 71.6868 6.09371 66.0919 12.2506C60.7344 18.1406 68.6972 26.7055 74.7532 21.6508Z\" fill=\"#FF5718\"><\/path><path d=\"M81.2355 135.577C81.3402 135.718 83.296 136.069 84.3857 136.988C86.5371 138.807 92.6489 144.065 91.3707 146.81C88.5697 152.833 81.6825 144.879 79.4403 141.945C78.5113 140.723 78.5393 139.2 78.4275 139.094C78.0992 138.771 71.6311 141.601 69.5915 141.643C57.7659 141.881 50.0335 127.532 58.2828 117.795C68.1246 106.183 85.6779 115.26 83.2821 130.284C83.0655 131.646 80.8164 135.023 81.2285 135.584L81.2355 135.577ZM59.582 128.571C59.7077 138.54 75.396 140.267 78.5951 131.182C83.7989 116.391 62.1944 110.704 58.8835 125.756C65.8406 126.907 63.0675 124.148 65.1211 121.27C67.2934 118.223 69.801 127.019 69.368 128.571C70.5903 128.55 70.2271 126.717 71.4425 126.1C73.3285 125.145 79.5172 125.026 78.4415 128.571C72.2178 127.63 72.7487 129.371 70.4018 134.201C67.7335 134.208 67.3912 128.459 66.56 126.472C64.6391 129.519 62.8999 128.529 59.582 128.578V128.571Z\" fill=\"#FF5718\"><\/path><path d=\"M88.9258 127.862L98.0133 111.02C99.7455 109.377 100.709 116.636 101.848 116.622C110.104 110.114 117.466 101.732 120.365 91.3628C123.068 91.7981 127.203 92.135 126.344 95.582C125.115 100.517 116.789 112.192 113.052 115.962C111.655 117.366 105.815 121.255 105.285 122.252C104.502 123.734 107.136 126.366 107.485 127.841C107.988 129.975 105.585 128.564 104.663 128.557C99.3613 128.522 94.1994 128.128 88.9328 127.869L88.9258 127.862Z\" fill=\"#FF5718\"><\/path><path d=\"M125.939 35.2001L125.241 54.148C124.347 55.0747 110.523 45.8851 108.491 44.6776L114.051 41.1674C109.476 35.179 103.643 29.661 97.0703 25.9543C95.5825 25.1119 90.5463 23.5393 90.3298 23.2374C89.6592 22.2967 92.3833 18.5619 91.7128 16.9402C93.7943 14.8341 110.377 26.9161 112.696 29.1977C114.337 30.8194 118.305 37.0184 119.667 37.6923C121.553 38.619 123.753 34.9474 125.932 35.2001H125.939Z\" fill=\"#FF5718\"><\/path><path d=\"M42.1055 35.1931C39.4721 35.7688 39.8982 29.7874 37.6211 30.3069C36.8039 30.4965 29.5046 38.2259 28.5616 39.4685C26.7665 41.8203 24.8735 45.0075 23.3927 47.6121C20.5778 52.5474 22.6383 54.2323 15.1714 50.673C18.4962 39.4895 26.494 30.2437 35.826 23.6165L32.3475 17.6562L49.4607 18.3513C50.0334 18.2951 51.165 19.0322 51.186 19.3973C51.2628 20.7031 42.4058 32.2867 42.1125 35.1931H42.1055Z\" fill=\"#FF5718\"><\/path><path d=\"M16.9735 92.76C20.0958 94.9994 31.5512 99.338 33.4022 101.879C34.3033 103.122 29.7561 104.821 28.848 104.702C27.5977 106.358 37.7539 115.021 39.3814 116.215C41.2254 117.563 50.9555 122.695 51.1091 123.369C51.3396 124.352 49.4677 127.047 49.768 128.536C47.2045 130.754 31.0972 118.356 28.5616 115.85C27.5837 114.881 23.288 109.012 22.8549 108.914C21.9329 108.696 18.3915 112.199 16.9666 112.41V92.7529L16.9735 92.76Z\" fill=\"#FF5718\"><\/path><path d=\"M112.416 68.2869L138.016 68.329C140.58 69.0942 140.538 76.7324 137.464 77.315C135.299 77.7222 114.847 77.6731 113.157 77.1746C110.377 76.3533 110.614 68.8766 112.416 68.2869Z\" fill=\"#FF5718\"><\/path><path d=\"M113.157 78.1575L138.044 78.1294C140.608 78.9929 140.866 86.5117 137.464 87.1435C135.243 87.5577 114.889 87.5156 113.157 87.0031C110.37 86.1817 110.37 78.9789 113.157 78.1575Z\" fill=\"#FF5718\"><\/path><path d=\"M138.163 58.3601C140.349 59.02 140.468 66.0965 138.366 67.0232C136.633 67.7814 114.107 67.8446 112.668 67.1426C110.153 65.914 111.508 58.3671 111.976 58.3671H138.17L138.163 58.3601Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_344\"><rect width=\"140\" height=\"149\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7266a44 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"7266a44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alta disponibilidade<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01ff403 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"01ff403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e89d42 e-flex e-con-boxed e-con e-parent\" data-id=\"7e89d42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ccccef animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3ccccef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como funciona<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5184b3e elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"5184b3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Um processo validado para ambientes cr\u00edticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9d0389 e-grid e-con-boxed e-con e-parent\" data-id=\"a9d0389\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a06bcb4 e-con-full e-flex e-con e-child\" data-id=\"a06bcb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d5757 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b7d5757\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254d9e2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"254d9e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2152_490)\"><path d=\"M120.03 97.7101C121.1 97.7301 122.1 97.4401 123.09 98.1501C125.66 100.02 122.8 121.19 124.24 126C126.14 132.36 141.53 137.27 135.91 148.08C132.6 154.44 125.14 151.95 124.14 152.81C123.76 153.14 122.92 159.55 119.02 161.18L22.52 161.72C18.16 161.47 14.3 157.72 14.02 153.22V26.1901C16.31 11.0401 33.07 18.9901 42.34 16.7401C43.52 16.4501 43.46 13.6001 45.73 12.9001C48.82 11.9401 53.82 13.5101 56.44 12.7801C57.39 12.5201 57.32 9.69006 58.17 8.35006C63.61 -0.129939 74.49 -0.10994 79.92 8.35006C80.78 9.69006 80.71 12.5101 81.65 12.7801C84.26 13.5001 89.27 11.9401 92.36 12.9001C94.62 13.6001 94.57 16.4501 95.75 16.7401C102.98 18.4901 118.66 12.9401 122.82 21.4501C124.25 24.3801 125.31 36.6401 121.55 36.7001C118.67 36.7501 122.22 20.7201 115.55 20.7201H96.05V25.7201H112.55C115.64 25.7201 116.98 38.4801 111.05 35.1501C111.63 27.3601 108.49 30.7901 103.59 30.7901C101.63 30.7901 97.19 29.9101 96.48 30.0401C95.09 30.2901 95.71 33.2601 91.61 33.7901C86.85 34.4001 46.06 34.5101 44.05 33.2301C43.04 32.5901 42.8 30.2201 41.47 29.8801C40.67 29.6801 37.46 30.8801 35.55 30.8301C33.64 30.7801 27.05 28.7701 27.05 31.2301V148.73H111.05C114.58 137.67 102.63 134.78 98.99 128.29C97.5 125.63 98.45 118.87 93.57 118.74C91.7 118.69 87.15 122.52 84.27 123.44C80.52 124.65 76.97 124.98 73.05 124.72C71.77 129.7 74.74 129.57 76.41 131.96C80.83 138.29 76.01 144.84 68.73 142.53C66.52 141.83 66.5 139.31 65.85 138.92C65.06 138.45 49.42 138.38 47.57 138.73C43.73 139.47 44 144.58 36.99 142.26C28.78 139.55 35.11 126.57 42.81 130.43C44.99 131.52 44.95 134.22 47.54 134.72C49.77 135.15 61.27 135.12 63.53 134.69C66.24 134.18 70.58 129.01 70.11 126.31C69.91 125.15 61.15 123.89 59.09 123.17C48.86 119.55 39.96 111.28 36.27 100.99C23.23 64.6601 65.86 33.7901 95.55 58.7001L95.12 43.2901C95.4 41.6701 96.03 39.4601 97.72 38.8901C110 38.5301 122.3 38.7801 134.59 38.7701C139.9 38.7701 147.57 35.7501 148.99 44.2801C149.94 50.0101 147.42 54.1701 147.42 57.2201C147.42 58.2801 148.88 59.7201 149 61.2701C149.24 64.4701 149.28 75.7201 144.55 75.7201H124.05C122.9 83.2901 128.25 87.1401 135.53 85.6901C139.14 84.9701 138.73 80.7301 144.31 81.9001C151.24 83.3401 150.58 94.7601 142.54 94.7701C137.38 94.7701 137.42 90.6101 135.38 89.8901C128.23 87.3401 127.08 94.7501 122.56 94.8101C117.36 94.8801 116.35 89.9501 115.34 89.7101C107.38 87.7901 109.8 90.8701 108.8 94.9901C107.8 99.1101 102.21 108.45 102.22 109.24C102.23 111.05 108.59 115.19 111.04 113.73V96.7301C112.79 96.5801 114.3 96.5101 114.88 98.3901C117.1 105.55 110.84 117.47 120.04 121.73V97.7301L120.03 97.7101ZM47.53 29.7101H90.53C92.48 29.7101 92.63 19.1401 91.59 17.6501C89.9 15.2301 80.38 18.0001 77.96 16.2801C75.92 14.8301 77.85 6.96006 69.54 6.62006C60.06 6.24006 62.32 14.6801 60.08 16.2801C58.01 17.7601 47.94 15.9201 47.07 16.7701C46.52 17.3101 44.81 28.8801 47.52 29.7201L47.53 29.7101ZM42.03 20.7101H22.53C20.27 20.7101 17.29 25.7201 17.98 28.1601C20.74 67.4901 14.47 111.48 17.98 150.25C18.24 153.12 18.55 155.39 21.03 157.2L115.48 157.6C122.82 156.58 120.81 147.16 115.05 144.69C115.12 146.29 115.48 152.69 113.54 152.69H24.53C24.42 152.69 23.03 151.3 23.03 151.19V26.7101C24.01 27.0301 25.2 25.7101 25.53 25.7101H42.03V20.7101ZM99.03 54.7101H143.53C145.75 54.7101 145.75 42.7101 143.53 42.7101H99.03V54.7101ZM73.69 54.1001C24.05 52.5801 27.41 127.86 78.27 120.46C115.2 115.08 113.31 55.3101 73.69 54.1001ZM144.94 59.8101C135.54 59.2201 125.96 60.0301 116.49 59.7601C113.17 59.6701 98.92 56.2101 98.99 61.2201C99.07 66.9401 112.11 62.3801 116.03 63.7301C116.83 70.1401 108.37 67.0801 104.04 67.7301C103.72 69.4201 105.3 71.0901 106.74 71.5201C109.78 72.4301 137.3 72.3001 141.58 71.7801C147.45 71.0601 144.45 64.6201 144.94 59.8301V59.8101ZM120.03 75.7101H107.03C108.77 77.3501 108.68 85.3401 109.04 85.7001C109.23 85.8901 113.58 85.8801 114.51 85.6901C118.7 84.8401 120.97 79.7401 120.04 75.7101H120.03ZM123.38 132.36C121.41 130.27 111.1 118.08 109.55 117.95C107.83 117.81 103.35 122.81 102.11 124.34C101.82 126.01 122.75 146.05 125.77 148.52C130.93 149.81 132.95 146.06 132.02 141.25C131.51 138.59 125.51 134.62 123.38 132.36Z\" fill=\"#FF5718\"><\/path><path d=\"M64.0301 39.7099C64.1701 39.8499 64.2301 43.7099 64.0301 43.7099H38.5301C38.2601 43.7099 37.6101 44.4999 36.7001 44.4599C32.7501 44.2699 32.3201 39.7099 34.5301 39.7099C38.5201 39.7099 63.0101 38.6499 64.0301 39.7099Z\" fill=\"#FF5718\"><\/path><path d=\"M69.84 56.9399C102.52 54.8099 114.57 101.52 84.72 114.91C39.25 135.3 22.95 59.9999 69.84 56.9399ZM69.03 103.71H54.53C51.51 103.71 51.73 94.2999 52.08 92.2599C52.38 90.4899 54.28 89.3199 54.07 87.2899C53.92 85.8799 52.3 84.7099 52.08 83.1599C51.67 80.3399 51.29 73.4099 53.61 71.7799C56.16 69.9799 87.9 70.0399 89.8 71.9399C91.26 73.3999 91.4 80.0899 91.09 82.2599C90.75 84.6299 88.81 86.2999 89 88.1199C89.15 89.5099 90.73 90.6799 90.99 92.2399C91.35 94.3899 91.53 103.69 88.54 103.69H73.04C75.1 107.02 72.58 110.07 73.04 113.69C102.13 112.37 107.39 70.4999 78.84 62.3899C42.72 52.1399 31.11 108.87 69.03 113.69V103.69V103.71ZM85.53 74.7099C82.09 73.6399 63.84 74.7099 58.53 74.7099C55.17 74.7099 55.94 79.3499 56.03 81.7099C62.19 81.8899 68.41 81.4699 74.58 81.6599C77.59 81.7499 85.71 84.6299 86.9 81.0599C87.45 79.4099 87.29 75.2399 85.54 74.6999L85.53 74.7099ZM87.03 92.7099H56.03V99.7099H87.03V92.7099Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_490\"><rect width=\"135.18\" height=\"159.74\" fill=\"white\" transform=\"translate(14 2)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ad9d9 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"b2ad9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assessment T\u00e9cnico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82492be elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82492be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4c331 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3d4c331\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Diagn\u00f3stico completo da infraestrutura<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f06167a e-con-full e-flex e-con e-child\" data-id=\"f06167a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb47d84 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb47d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d474ce elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8d474ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2152_497)\"><path d=\"M76.0801 31.57C75.7401 29.47 73.3101 26.46 73.2501 23.6C73.2101 22.04 76.3501 9.32001 77.0601 8.54001C78.7901 6.64001 85.4501 6.53001 87.4501 7.97001C88.2901 8.57001 91.8901 22.65 91.7601 24.43C91.5501 27.4 88.5401 31.32 88.2801 34.85C87.8301 40.85 89.0601 48.6 89.1201 54.52C89.2201 63.68 88.5501 72.95 89.5701 82.06L122.93 47.4L123.06 46.09C120.59 45.88 113.32 38.27 115.11 36.11C125.66 34.47 136.38 30.25 146.66 28.15C148.48 27.78 156.72 26.08 157.66 26.1C158.86 26.13 159.56 26.59 159.99 27.71C158.52 33.56 152.59 70.72 150.11 72.59C147.27 74.73 141.33 62.83 138.09 64.5L97.5901 105.07C95.1001 120.07 100.49 137.11 94.0801 151.06H123.08C124.93 141.82 117.52 144.9 111.37 141.27C105.22 137.64 99.8601 127.82 102.22 120.7C103.97 115.42 120.06 121.65 123.07 125.06C122.88 121.61 123.39 118.01 123.07 114.58C122.02 103.7 113 99.97 120.25 88.72C124.04 82.84 126.25 82.9 129.73 88.92C135.99 99.74 129.03 102.46 127.1 112.06C132.79 106.34 138.33 102.21 146.67 101.14C155.01 100.07 157.44 99.86 157.13 108.6C156.53 125.87 144.37 137.2 127.08 136.05V151.05H156.58C158.17 151.05 160.24 156.05 157.58 156.05H5.58007C5.24007 156.05 3.72007 154.4 4.04007 153.55C24.3601 131.2 46.8501 110.17 68.0901 88.49C68.8501 87.81 69.3001 88.09 70.0701 88.49C73.5501 90.29 86.8801 107.43 89.4401 106.98L137.26 58.26C141.63 56.29 145.73 66.68 148.06 65.04L155.06 32.53C144.02 32.22 133.03 37.4 122.08 39.06C121.34 40.04 131.3 46.2 127.98 49.37L89.4401 87.98C87.5101 88.32 71.6701 70.42 68.5801 68.07L5.60007 130.07C4.40007 128.97 3.66007 128.81 4.56007 127.06C6.44007 123.42 16.8101 115.35 19.9501 111.49C22.5201 93.22 20.4001 74.14 21.0601 55.6C20.4701 52.63 17.1401 51.9 15.0801 49.58C5.44007 38.66 6.52007 19.75 18.5901 11.08C19.9101 10.13 27.0901 5.92001 27.0901 9.58001V29.58C27.0901 30.02 33.6701 34.01 34.5801 34.05C35.0601 34.07 42.6801 30.32 42.9301 29.93C44.6601 27.19 41.6801 13.42 42.2701 10.39C43.7501 2.85001 55.7001 15.24 57.6501 19.03C63.3301 30.1 61.6601 40.82 53.6301 50.12C52.6101 51.3 48.0901 53.78 48.0901 54.58V82.08C52.5501 79.95 64.6501 63.95 67.7901 63.18C71.3101 62.32 73.6401 67.72 76.0901 69.08C74.7801 57.72 77.8601 42.44 76.0901 31.58L76.0801 31.57ZM85.0401 12.13C84.8301 11.93 80.3401 11.93 80.1301 12.13C79.7401 12.5 78.0301 21.45 78.0001 22.58C77.9101 26.56 79.7101 28.25 80.1101 31.55C81.5601 43.48 78.4801 58.63 80.1701 70.49C80.5401 73.09 81.4701 75.42 83.5801 77.08C85.5001 63.54 82.7001 49.1 84.0901 35.6C84.5101 31.54 86.9101 27.82 87.1501 24.58C87.2401 23.3 85.4901 12.57 85.0301 12.14L85.0401 12.13ZM22.0801 30.57C21.0001 26.71 22.8701 18.51 22.0801 14.07C11.2901 20.82 10.0801 36.33 17.6501 46C19.0801 47.82 25.0801 52.08 25.0801 52.57V106.07C26.8601 105.62 27.9401 102.15 28.1301 100.61C29.3501 90.61 25.8101 70.75 29.0101 62.49C32.2301 54.19 41.0801 59.65 41.0801 63.56V90.06C42.6501 89.56 43.7501 88.14 44.0601 86.54C45.7901 77.65 41.9501 60.74 44.2901 52.77C45.0001 50.36 48.9001 48.95 50.6201 47.1C59.3401 37.71 58.8201 20.51 47.0801 14.06V30.56C47.0801 32.05 36.8301 38.71 35.4301 38.85C33.5601 39.03 22.5401 32.2 22.0801 30.56V30.57ZM33.0801 97.07C33.8201 97.05 36.0801 94.77 36.0801 94.57V63.57C36.0801 62.09 33.0801 62.09 33.0801 63.57V97.07ZM71.0801 151.07C70.4501 147.99 68.4801 147.21 68.0601 143.59C67.0501 135.04 67.0401 111.07 68.0601 102.54C68.4601 99.21 69.9601 98.33 71.0901 95.59C70.3701 94.88 69.8301 93.8 68.6001 94.07C66.7201 94.48 51.5501 112.24 48.2901 114.77C46.4001 126.31 51.4401 141.12 45.0901 151.07H71.0901H71.0801ZM93.0801 110.07C91.4801 110.36 90.4901 113.31 88.7201 113C87.4401 112.77 78.4201 102.42 76.0801 100.57C74.8501 99.6 75.0401 98.41 73.5901 100.08C72.5001 101.33 72.2401 102.96 72.0601 104.55C71.3401 111.07 71.1401 138.62 72.5501 144.1C75.5101 155.59 93.0801 151.63 93.0801 143.57V110.07ZM152.08 105.07C138.49 105.53 126.19 113.26 127.09 128.07C130.02 126.96 137.9 116.45 139.59 116.07C140.82 115.8 141.35 116.87 142.07 117.58C142.96 120.97 132.6 127.58 131.07 131.05C146.16 131.84 153.72 118.91 152.07 105.06L152.08 105.07ZM44.0801 119.07C40.0801 123.79 28.7501 131.78 26.0301 136.51C20.4701 146.17 33.5101 156.07 41.6001 149.09C42.1701 148.6 44.0801 145.95 44.0801 145.57V119.07ZM122.07 135.07C121.51 125.74 113.91 124.03 106.09 123.08C106.62 130.48 109.74 138.28 118.08 139.07C119.77 137.59 108.17 130.18 113.6 129.08C115.02 128.79 121.71 135.55 122.07 135.08V135.07Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_497\"><rect width=\"156\" height=\"149.07\" fill=\"white\" transform=\"translate(4 7)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41db3af elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"41db3af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desenho de Arquitetura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b14817 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7b14817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46d791e elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"46d791e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Defini\u00e7\u00e3o da melhor estrat\u00e9gia cloud<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5afadb9 e-con-full e-flex e-con e-child\" data-id=\"5afadb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5698558 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5698558\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-605b9ed elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"605b9ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2152_505)\"><path d=\"M58.4801 71.49C60.1701 72.99 58.6301 77.02 61.3201 79.16C68.5001 84.89 68.8901 79.84 73.7201 78.67C77.6301 77.72 85.5701 86 84.5501 90.54C83.9501 93.21 81.3001 93.75 81.8801 97.5C83.0401 104.96 90.6901 103.11 92.2301 106.25C93.0201 107.86 93.0801 115.79 92.7201 117.76C91.9201 122.19 85.3101 120.5 83.6501 122.94C78.9701 129.79 85.7501 133.27 84.5801 137.54C84.3801 138.29 77.4701 145.42 76.7001 145.78C71.9501 147.98 69.4101 142.11 67.4401 142.42C67.0901 142.47 61.2101 145.24 60.9601 145.49C59.2401 147.21 60.6601 152.32 57.7501 153.78C56.1301 154.59 48.2401 154.62 46.2601 154.25C41.1301 153.27 42.7601 146.85 41.5501 145.46C41.2901 145.16 34.6101 142.52 34.2201 142.55C32.8301 142.66 30.5401 147.6 25.4501 146.11C24.7001 145.89 18.1701 139.66 17.6801 138.83C14.5201 133.52 21.2601 132.72 20.5601 128.02C19.4201 120.43 11.6501 122.2 10.2201 119.3C9.79006 118.43 8.97006 109.5 9.17006 108.23C10.1801 101.72 16.3301 104.53 18.2501 102.29C18.5601 101.93 20.7401 96.27 20.7301 95.75C20.6801 93.45 16.0001 91.37 16.8801 87.99C17.0501 87.34 25.1101 79.03 25.7701 78.75C29.1201 77.33 32.0501 82.12 34.0401 82.1C34.8101 82.1 41.0901 79.52 41.4901 79.03C42.8301 77.34 41.9401 72.16 44.7301 70.77C46.8101 69.73 56.8901 70.08 58.5001 71.52L58.4801 71.49ZM55.6501 75.33C54.9401 74.58 47.9101 74.8 46.6901 75.74C44.7001 77.26 46.3901 80.95 45.5901 82.14C45.2001 82.72 34.2601 86.66 32.4401 86.11C29.8801 85.33 29.9401 81.46 25.1701 84.23C17.1501 88.89 25.3101 92.98 25.5601 95.94C25.6101 96.57 20.6801 106.94 20.0801 107.13C17.4801 107.96 14.5001 105.86 13.7301 109.77C11.7501 119.76 18.2301 116.08 21.2301 119.27C21.5901 119.66 25.5201 128.4 25.5701 128.93C25.7901 131.28 20.5601 134.86 21.1801 136.27C28.6701 146.65 28.9801 138.33 34.2201 138.33C34.7601 138.33 43.6401 141.97 44.1501 142.34C46.7701 144.27 45.4101 149.85 47.3901 150.31C48.3101 150.52 55.3801 150.51 55.6801 150.22C56.0501 149.86 56.1101 143.61 56.9301 142.48C57.2601 142.02 66.8601 138.5 67.4701 138.41C70.8701 137.94 73.1601 143.07 75.7001 141.83C76.6701 141.35 80.0501 137.44 80.2901 136.35C80.8001 134.03 77.1401 131.81 76.9301 129.61C76.8801 129.05 80.2901 119.34 80.6201 118.88C81.6901 117.38 88.5701 117.95 88.7801 116.68C90.6201 103.9 85.4301 109.8 81.1201 106.36C80.7001 106.03 76.9401 97.07 76.8601 96.52C76.3801 93.14 81.5501 90.79 80.2901 88.28C79.9601 87.63 75.6701 83.53 75.0201 83.36C72.5701 82.73 70.7401 86.49 67.3001 86.24C66.7501 86.2 59.0401 83.42 58.4201 83.06C54.6301 80.85 56.2601 75.95 55.6601 75.32L55.6501 75.33Z\" fill=\"#FF5718\"><\/path><path d=\"M139.72 16.2601C143.27 12.5701 149.94 4.89009 154.77 9.71009C160.48 15.4101 152.93 19.9201 149.68 23.7701C148.96 24.6201 148.94 26.0101 148.72 26.2701C155.62 28.1701 157.82 42.6201 157.8 48.7701C157.72 70.2401 137.92 91.2601 116.21 91.3501C112.14 91.3701 101.36 87.8701 99.33 88.2001C98.25 88.3701 97.88 92.7601 96.22 93.2601C94.49 93.2801 86.37 74.6501 88.14 72.2201C88.98 71.0601 107.53 67.1801 108.72 68.2901C109.18 69.5501 107.3 72.8301 107.72 73.2801C108.11 73.7001 114.88 74.3901 116.23 74.3501C126.89 74.0601 138.18 64.8301 140.29 54.3501C141.18 49.9101 139.11 36.9501 139.73 36.2901C140.6 35.3701 142.67 36.5001 143.54 37.9701C147.06 43.9201 145.35 54.5901 142.6 60.6501C136.44 74.2601 123.1 80.4801 108.47 78.0401C103.51 77.2101 101.52 73.2901 101.07 73.2101C99.96 73.0201 92.43 74.6901 92.73 76.7301C92.91 77.9501 95.49 84.2901 96.22 84.2601C96.48 84.2501 97.53 82.3201 99.05 82.4301C100.65 82.5501 105.58 85.7101 109.33 86.1701C135.44 89.3201 155.36 68.8601 152.59 42.9101C151.92 36.6401 148.17 32.4301 148.71 26.2801C145.71 29.6901 140.96 33.1301 137.68 36.7501C133.67 41.1701 118.11 60.1801 114.69 61.7701C110.6 63.6801 106.9 60.0001 104.18 57.3001C100.7 53.8601 93.18 46.2201 97.01 41.5701C102.03 35.4701 108.55 43.6001 112.2 47.2601C119.62 38.0401 128.01 29.7901 136.21 21.2901C137.65 19.8001 138.47 17.5501 139.7 16.2801C138.69 17.2401 128.13 11.7601 125.46 11.0201C92.31 1.81009 67.27 36.2601 81.71 66.2801C82.06 66.5501 87.42 60.0801 87.51 59.6501C87.77 58.3501 84.71 50.8601 84.71 47.7801C84.71 26.3601 110.33 8.59009 129.4 21.0801C130.36 21.7101 132.05 22.1701 131.7 23.7601C130.8 27.8401 123.26 22.6701 121.14 22.3401C102.66 19.4001 84.14 35.3201 90.35 54.1301C91.27 56.9201 93.76 57.5001 93.7 57.7601C93.49 58.6301 83.97 71.9301 83.12 72.2001C79.61 73.3201 78.11 65.1201 75.66 62.8201C73.98 61.2501 70.14 60.5201 68.71 57.7701L74.7 57.2701C67.97 27.4001 91.48 1.58009 122.11 5.37009C124.46 5.66009 143.75 12.4501 139.72 16.2601ZM151.71 12.2601C149.83 11.8301 149.34 13.3301 148.21 14.2501C135.87 24.3801 125.19 40.4201 113.7 51.7901C108.77 54.0701 104.86 40.9301 99.74 45.7501C103.93 48.1901 108.91 59.0001 113.71 56.7501L150.77 16.8001L151.71 12.2501V12.2601Z\" fill=\"#FF5718\"><\/path><path d=\"M51.92 17.03C54.03 20.12 57.88 15.51 59.21 15.58C59.82 15.61 64.28 18.93 64.79 19.69C67.22 23.31 63.96 26.15 64.79 28.63C65.42 30.52 69.2 30.19 70.24 32.25C71.01 33.77 71.04 38.05 70.72 39.77C69.98 43.68 65.27 42.75 64.77 43.32C63.49 44.78 66.61 48.82 66.28 50.35C65.93 51.96 60.85 57.32 59.23 57.28C57.61 57.24 55.96 54.39 53.32 55.32C50.97 56.14 52.95 61.93 47.27 62.11C46.41 62.14 41.08 61.12 40.67 60.81C39.14 59.68 40.96 54.88 36.21 55.33C32.78 55.66 31.63 59.61 26.72 53.49C22.97 48.82 25.96 49.18 26.71 45.69C27.63 41.39 22.76 43.65 21.18 41.3C20.51 40.3 20.36 33.26 20.68 31.92C21.1 30.14 27.38 31.41 26.76 26.83C26.53 25.13 24.33 23.96 24.83 21.98C25.03 21.21 30.77 15.44 31.37 15.34C33.24 15 34.17 18.9 37.05 18.18C41.13 17.16 36.81 9.04002 48.21 11.31C52.7 12.2 50.85 15.45 51.94 17.05L51.92 17.03ZM47.65 15.31C47.49 15.16 43.93 15.16 43.78 15.31C43.48 15.61 44.03 18.11 43.25 19.28C42.96 19.71 37.7 21.99 36.94 22.1C33.62 22.6 32.42 20.02 31.24 20.25C27.73 20.94 31.51 25.4 31.5 26.57C31.5 27.15 29.18 33.2 28.83 33.64C28.07 34.59 21.82 33.71 24.85 38.11C25.39 38.9 28.97 38.77 29.54 39.44C29.76 39.7 31.51 45.6 31.54 45.93C31.68 47.38 29.23 48.75 29.72 50.73C30.6 54.33 34.94 50.33 36.04 50.43C36.38 50.46 42.24 52.24 42.52 52.44C43.61 53.22 43.14 56.99 44.28 57.31C49.44 58.77 46.91 54.96 47.88 53.43C48.07 53.12 54.09 50.44 54.47 50.38C56.83 50.05 58.14 52.74 60.2 52.25C63.38 51.5 59.87 47.58 59.95 45.93C59.97 45.48 61.49 40.37 61.71 39.98C62.81 37.99 66.43 38.9 66.77 37.69C68.19 32.71 64.53 35 62.69 33.78C62.3 33.52 59.93 28.15 59.84 27.48C59.52 25 62.24 24.18 61.27 22.25C59.25 18.23 57.04 22.13 55.21 22.21C54.73 22.23 49.02 20.04 48.68 19.75C47.1 18.37 47.98 15.64 47.63 15.29L47.65 15.31Z\" fill=\"#FF5718\"><\/path><path d=\"M125.97 99.9799C127.87 102.37 130.21 98.5899 133 99.3799C133.77 99.5999 137.91 103.56 138.27 104.28C139.33 106.4 136.06 108.45 136.76 110.64C137.41 112.68 145.19 112.04 142.52 120.56C141.61 123.48 137.32 123.01 136.75 124.85C136.25 126.47 141.05 132.57 133.67 135.78C130.86 137 129.8 134.47 127.6 134.7C124.7 135.01 125.5 139.28 123.04 140.09C121.96 140.44 115.03 140.49 114.75 140.2C114.41 139.85 115.26 135.99 112.7 134.68C110.93 133.78 105.39 139.31 102.19 132.22C100.89 129.35 103.35 126.96 102.65 124.89C101.95 122.82 95.3201 123.59 96.8901 116C97.7701 111.71 101.25 112.69 102.3 111.3C103.44 109.78 99.0601 102.76 105.75 99.7399C108.58 98.4599 112.32 101.14 113.64 100.19C115.47 98.8699 111.41 93.6999 121.27 95.2199C126.42 96.0099 124.34 97.9399 125.97 99.9899V99.9799ZM121.57 99.4299C118.19 96.4599 117.58 101.83 116.8 102.81C113.62 106.82 106.14 103.24 105.71 105.78C107.97 108.65 107.51 111.56 105.54 114.59C104.48 116.22 99.4601 116.63 101.74 119.21C102.31 119.86 106.42 118.78 107.32 125.22C107.66 127.68 104.16 131.55 108.07 131.11C110.48 130.84 112.86 128.39 116.74 131.74C118.36 133.14 117.18 136.08 118.22 136.27C123.08 137.12 121.02 134.84 122.66 132.72C126.1 128.27 131.3 131.69 132.73 130.76C135.1 129.22 132.04 127.98 132.17 126.18C132.67 119.36 138.16 119.42 138.72 116.74C135.57 116.13 132.84 113.42 132.11 110.24C131.49 107.56 135.22 106.6 132.74 104.73C131.34 103.81 129.02 105.42 126.05 104.51C121.29 103.04 122.3 100.04 121.59 99.4199L121.57 99.4299Z\" fill=\"#FF5718\"><\/path><path d=\"M94.7401 145.25C94.4901 145.07 94.3301 142.18 92.7301 142.26C88.9101 149.78 77.9901 157.85 69.7401 159.81C66.4201 160.6 65.3201 157.39 68.4201 155.47C70.7101 154.05 74.9701 153.11 77.6001 151.65C83.2201 148.53 86.2801 144.2 90.7001 139.75C81.4401 139.66 91.2601 133.55 94.6701 132.69C99.8501 131.37 98.8501 148.12 94.7301 145.25H94.7401Z\" fill=\"#FF5718\"><\/path><path d=\"M29.71 70.26C28.64 68.99 14.89 81.41 13.31 83.35C11.83 85.16 9.78001 90.05 8.74001 90.82C6.82001 92.25 5.13001 89.75 6.50001 86.55C9.16001 80.33 17.29 72.58 23.2 69.24C24.75 68.36 28.53 67.47 28.72 67.25C28.98 66.94 25.76 64.06 26.73 62.27C28.86 61.68 37.28 63.78 37.72 65.83C37.86 66.5 32.96 73.9 32.12 74.16C27.64 75.56 29.92 70.5 29.72 70.26H29.71Z\" fill=\"#FF5718\"><\/path><path d=\"M148.71 126.27C152.23 129.88 139.77 143.04 136.04 145.09C133.41 146.53 119.79 151.49 119.73 146.77C119.7 144.43 128.46 143.57 130.69 142.75C134.39 141.39 138.11 138.67 140.54 135.6C141.9 133.87 146.11 123.61 148.71 126.28V126.27Z\" fill=\"#FF5718\"><\/path><path d=\"M34.0601 128.92C18.2801 112.43 33.5601 85.19 55.9901 89.49C58.3201 89.94 60.9601 92.26 62.2501 92.27C64.2401 92.28 68.2001 85.69 73.1801 91.3C77.1201 95.73 71.8301 98.96 71.7701 101.76C71.7301 103.34 73.5001 104.96 73.6801 106.81C74.5201 115.53 73.7801 122.98 67.2701 129.3C58.2801 138.02 42.8001 138.03 34.0701 128.91L34.0601 128.92ZM60.7201 95.27C42.1901 86.53 23.6301 107.09 35.7301 123.75C48.6401 141.54 76.5201 126.36 68.7101 105.26C62.3201 109.46 55.6101 129.78 46.1601 124.31C45.5801 123.97 37.0001 115.4 36.6701 114.82C31.5201 105.91 44.4101 101.14 49.2201 110.25L60.7201 95.28V95.27ZM69.7101 93.26C69.0601 92.56 66.4501 94.18 65.6801 95C62.2601 98.62 56.7901 106.79 53.2501 111.31C51.4201 113.65 52.5001 117.09 47.7301 114.74C45.4301 113.61 43.7201 108.34 39.7201 110.75C41.1601 112.93 48.2001 122.09 50.7101 120.82C55.1001 118.59 63.7901 101.54 68.7601 97.8C69.7001 97.02 70.1101 93.7 69.7101 93.26Z\" fill=\"#FF5718\"><\/path><path d=\"M44.51 23.4801C62.13 21.4701 63.83 51.7701 43.32 49.1801C29.38 47.4201 28.72 25.2901 44.51 23.4801ZM44.49 27.4301C32.91 28.9001 34.63 46.5201 47.13 45.2501C58.35 44.1101 55.98 25.9701 44.49 27.4301Z\" fill=\"#FF5718\"><\/path><path d=\"M116.43 106.47C132.26 102.83 136.88 125.39 122.98 129.01C107.05 133.15 103.68 109.41 116.43 106.47ZM114.02 112.55C106.12 122.35 125.55 131.9 126.75 118.76C127.57 109.78 118.05 107.55 114.02 112.55Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_505\"><rect width=\"151.8\" height=\"154.93\" fill=\"white\" transform=\"translate(6 5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df9da7c elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"df9da7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Implementa\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a13b26 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4a13b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2630dd6 elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2630dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Execu\u00e7\u00e3o com testes e valida\u00e7\u00f5es cont\u00ednuas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a89e25d e-con-full e-flex e-con e-child\" data-id=\"a89e25d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5386779 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5386779\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">04<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0544b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8e0544b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"164\" height=\"164\" viewBox=\"0 0 164 164\" fill=\"none\"><g clip-path=\"url(#clip0_2152_512)\"><path d=\"M83.1801 106.6C85.5901 114.56 82.7901 121.93 83.1301 129.95C83.4101 131.12 92.4701 133.16 93.7001 135.58C94.3801 136.92 94.6301 149.29 94.2201 150.93C94.0501 151.62 83.0401 157.52 81.6801 157.52C80.1401 157.52 70.1801 152.4 69.2801 150.99C67.8101 148.69 67.5301 138.94 68.6701 136.58C70.0201 133.79 79.1801 131.19 79.1801 130.59V106.59H26.6801C26.3001 106.59 20.8601 103.93 19.8501 103.42C0.460113 93.49 -1.92989 64.57 17.0301 52.95C19.4001 51.5 25.6101 49.83 26.6501 48.57C28.0301 46.91 29.0801 39.44 31.7301 35.65C38.7401 25.64 52.6501 21.98 63.5601 27.51C82.3101 -4.78996 129.9 2.23004 136.06 40.19C136.45 42.61 135.51 46.97 136.62 48.63C137.3 49.64 143.17 51.12 145.05 52.2C162.3 62.2 164.66 86.51 149.63 99.55C147.57 101.34 138.84 106.58 136.66 106.58H83.1601L83.1801 106.6ZM128.18 102.6C156.38 104.55 166.05 65.68 139.87 54.41C137.86 53.54 132.52 52.95 131.63 51.64C130.09 49.36 132.27 46.45 132.18 44.1C130.98 14.55 94.1501 -0.199963 73.6601 21.57C71.6701 23.68 66.4201 33.43 65.7001 33.49C65.2101 33.53 59.7001 29.95 56.7101 29.57C41.6801 27.68 31.2701 37.72 31.0801 52.5C-1.79989 57.32 2.10011 102.68 35.1801 102.6V80.1C38.1301 78.07 48.1501 71.1 50.9301 70.74C54.1001 70.33 60.0001 75.7 62.8301 76.48C64.3001 76.89 65.1801 74.58 65.1801 74.1V53.1C65.1801 52.73 63.7901 51.69 64.6101 50.65C65.5201 48.69 80.6401 40.45 82.4601 40.75C83.3201 40.89 97.3601 48.19 97.9201 48.86C100.01 51.41 98.6601 56.63 98.1801 59.6H113.18C113.7 62.67 112.2 69.2 113.67 71.61C115.14 74.02 126.24 76.54 128.18 80.1V102.6ZM91.1801 51.58C90.1401 49.95 82.8901 45.67 81.7001 45.63C79.1901 45.54 75.1901 49.59 72.1901 49.6C71.6601 51.85 72.5201 51.22 73.4301 51.88C81.4701 57.72 83.1201 55.01 91.1801 51.57V51.58ZM79.1701 71.6C78.6701 68.73 80.1401 61.66 78.7101 59.57C78.0401 58.58 70.7901 55.91 69.1901 54.6C68.1101 65.71 68.9301 67.75 79.1701 71.6ZM83.1901 71.6C93.9901 68.3 95.4301 66.15 94.1701 54.6C92.6101 55.66 83.8201 59 83.3401 59.76C82.3501 61.33 83.7001 69.07 83.1901 71.6ZM109.19 63.59H99.1801L99.1901 76.59C106.31 74.5 110.89 71.83 109.19 63.59ZM79.0501 75.73C78.7601 75.28 70.5401 73.09 69.2001 71.59C69.7201 74.13 68.3601 81.85 69.3501 83.43C69.6301 83.88 77.6701 87.24 79.1801 87.58C78.6601 85.12 79.9801 77.17 79.0501 75.72V75.73ZM94.1801 71.6C84.3001 74.51 81.6701 76.74 83.1901 87.59C83.5801 88.03 93.7101 83.93 94.0201 83.43C95.0101 81.85 93.6501 74.14 94.1801 71.59V71.6ZM61.1801 79.61C52.6101 74.99 48.7601 74.82 41.1801 81.58C44.3801 81.03 49.6301 86.22 51.6701 86.24C52.7201 86.25 58.7401 82.8 59.9201 81.88C60.7301 81.24 61.7601 81.9 61.1801 79.61ZM121.18 81.58C120.14 79.95 112.88 75.67 111.7 75.63C109.66 75.56 103.22 79.67 101.19 81.09C109.15 86.1 113.08 86.91 121.18 81.57V81.58ZM65.1801 101.1C66.3501 97.31 64.3201 88.11 65.1801 83.6C63.1001 85.11 56.5101 87.59 55.1701 89.09C52.9401 91.57 54.7501 99.13 54.1801 102.61C56.6001 102.3 64.3901 103.67 65.1901 101.1H65.1801ZM39.1801 84.6V102.6H50.1801C49.3301 100.11 50.2001 90.18 48.9801 88.79C48.6301 88.39 40.6401 85.36 39.1701 84.6H39.1801ZM99.1801 84.6V100.1C99.1801 100.32 97.3201 101.83 99.8001 102.48C102.48 103.18 106.31 102.26 109.19 102.6C108.62 99.12 110.43 91.57 108.2 89.08C106.9 87.62 101.13 86.16 99.1901 84.59L99.1801 84.6ZM124.18 102.6V84.6C113.75 88.63 111.81 90.9 113.17 102.61H124.18V102.6ZM69.1801 87.6V102.6H79.1901C80.7901 91.6 77.6101 91.85 69.1801 87.6ZM94.1801 102.6V87.6C85.8201 91.01 83.2201 92.36 83.1701 102.09L94.1801 102.6Z\" fill=\"#FF5718\"><\/path><path d=\"M54.1799 117.6V132.1C54.1799 135.14 32.0299 132.81 28.8899 133.58C27.7299 133.86 26.5199 140.29 20.5999 140.59C9.83991 141.13 8.25991 123.73 20.0499 123.12C26.6599 122.78 28.2399 129.5 28.8399 129.65C30.5399 130.07 48.1899 129.74 49.2399 129.13C49.8799 124.43 48.1399 118.64 50.1899 113.6H74.6899C76.4099 113.6 76.4099 117.6 74.6899 117.6H54.1899H54.1799Z\" fill=\"#FF5718\"><\/path><path d=\"M113.18 113.6V129.6H135.18C135.38 129.6 135.4 127.08 136.46 125.88C144.45 116.88 158.74 129.83 149.15 138.07C140.8 145.24 137.57 135.02 133.47 133.81C130.16 132.83 109.18 135.05 109.18 132.1V117.6H88.6799C86.9599 117.6 86.9599 113.6 88.6799 113.6H113.18Z\" fill=\"#FF5718\"><\/path><\/g><defs><clipPath id=\"clip0_2152_512\"><rect width=\"155.6\" height=\"150.52\" fill=\"white\" transform=\"translate(4 7)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-400051a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"400051a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sustenta\u00e7\u00e3o e Evolu\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1795c0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b1795c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fc0f4b elementor-widget__width-initial elementor-widget-mobile__width-inherit animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0fc0f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Monitoramento e otimiza\u00e7\u00e3o cont\u00ednua<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e10c2c e-flex e-con-boxed e-con e-parent\" data-id=\"7e10c2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f1b63e e-con-full e-flex e-con e-child\" data-id=\"4f1b63e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_effects_offset&quot;:90,&quot;sticky_anchor_link_offset&quot;:90}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1def2af animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1def2af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EXPERTISE NOS PRINCIPAIS ERPS DO MERCADO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fed1366 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"fed1366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Migra\u00e7\u00e3o completa de ERPs com foco em continuidade operacional<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7a048 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b7a048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d73b6b5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d73b6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"13\">ERPs s\u00e3o sistemas cr\u00edticos. Qualquer falha impacta diretamente o neg\u00f3cio. Por isso, nossa abordagem vai al\u00e9m da migra\u00e7\u00e3o simples.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edebf91 e-con-full e-flex e-con e-child\" data-id=\"edebf91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6baeddf elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"6baeddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O que fazemos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91a758f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"91a758f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"13\">Realizamos a migra\u00e7\u00e3o completa de toda a pilha tecnol\u00f3gica de ERPs como:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d4ebc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"47d4ebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TOTVS Protheus<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TOTVS Linha RM<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">MV Soul<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Winthor<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sankhya<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eae9a0f e-con-full e-flex e-con e-child\" data-id=\"eae9a0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d622ab e-con-full e-flex e-con e-child\" data-id=\"5d622ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-dc8a52a e-con-full e-flex e-con e-child\" data-id=\"dc8a52a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca52b1 elementor-widget elementor-widget-image\" data-id=\"2ca52b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-75.svg\" class=\"attachment-large size-large wp-image-1354\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3eb751 e-con-full e-flex e-con e-child\" data-id=\"e3eb751\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24f716a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"24f716a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Banco de dados<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7768df8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7768df8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30fb446 elementor-widget elementor-widget-text-editor\" data-id=\"30fb446\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Migra\u00e7\u00e3o, tuning e alta disponibilidade<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e6dad3 e-con-full e-flex e-con e-child\" data-id=\"9e6dad3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-0d7fc03 e-con-full e-flex e-con e-child\" data-id=\"0d7fc03\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-195050c elementor-widget elementor-widget-image\" data-id=\"195050c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-76.svg\" class=\"attachment-large size-large wp-image-1355\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c764786 e-con-full e-flex e-con e-child\" data-id=\"c764786\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c39589e elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"c39589e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servidores de aplica\u00e7\u00e3o<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab01a2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6ab01a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef288f elementor-widget elementor-widget-text-editor\" data-id=\"1ef288f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Instala\u00e7\u00e3o e Reconfigura\u00e7\u00e3o completa para cloud<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f816ceb e-con-full e-flex e-con e-child\" data-id=\"f816ceb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-0bd92e5 e-con-full e-flex e-con e-child\" data-id=\"0bd92e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2b7672 elementor-widget elementor-widget-image\" data-id=\"a2b7672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-77.svg\" class=\"attachment-large size-large wp-image-1356\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be2c9c e-con-full e-flex e-con e-child\" data-id=\"5be2c9c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34501af elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"34501af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Integra\u00e7\u00f5es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c7579 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"84c7579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43aa4be elementor-widget elementor-widget-text-editor\" data-id=\"43aa4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Garantia de funcionamento ponta a ponta<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0616fe9 e-con-full e-flex e-con e-child\" data-id=\"0616fe9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-3c1740e e-con-full e-flex e-con e-child\" data-id=\"3c1740e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e05a0c9 elementor-widget elementor-widget-image\" data-id=\"e05a0c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-78.svg\" class=\"attachment-large size-large wp-image-1357\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5df9fd9 e-con-full e-flex e-con e-child\" data-id=\"5df9fd9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7eb9f elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"4b7eb9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Seguran\u00e7a<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf2b1f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ecf2b1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d508c elementor-widget elementor-widget-text-editor\" data-id=\"42d508c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Controle de acessos e pol\u00edticas de prote\u00e7\u00e3o<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88f4e12 e-con-full e-flex e-con e-child\" data-id=\"88f4e12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-4ffec2f e-con-full e-flex e-con e-child\" data-id=\"4ffec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7f69e5 elementor-widget elementor-widget-image\" data-id=\"f7f69e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"164\" height=\"164\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/Frame-79.svg\" class=\"attachment-large size-large wp-image-1358\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66b0168 e-con-full e-flex e-con e-child\" data-id=\"66b0168\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82d2dfb elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"82d2dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Backup e Disaster Recovery<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f78983b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f78983b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311e5e8 elementor-widget elementor-widget-text-editor\" data-id=\"311e5e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Estrat\u00e9gia completa de recupera\u00e7\u00e3o<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-584aa54 e-flex e-con-boxed e-con e-parent\" data-id=\"584aa54\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7a1f5f e-con-full e-flex e-con e-child\" data-id=\"f7a1f5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-382d68b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"382d68b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Resultado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94adaa0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"94adaa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O ERP \u00e9 entregue:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be5f1e1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"be5f1e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Totalmente funcional<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Testado e validado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Otimizado para performance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pronto para uso em produ\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd6256b e-con-full e-flex e-con e-child\" data-id=\"bd6256b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85d183e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"85d183e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Benef\u00edcios para o cliente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a64126 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9a64126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Migra\u00e7\u00e3o sem impacto na opera\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Melhor performance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alta disponibilidade<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Redu\u00e7\u00e3o de riscos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ambiente preparado para crescimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed4f274 e-flex e-con-boxed e-con e-parent\" data-id=\"ed4f274\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-216e686 animated-slow elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"216e686\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RESULTADOS ESPERADOS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26634f9 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"26634f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impacto direto no seu neg\u00f3cio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eeceaa4 e-flex e-con-boxed e-con e-parent\" data-id=\"eeceaa4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-theme=\"\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-941b2d9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"941b2d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"15\" viewBox=\"0 0 59 15\" fill=\"none\"><path d=\"M58.7071 8.07112C59.0976 7.6806 59.0976 7.04743 58.7071 6.65691L52.3431 0.292946C51.9526 -0.0975785 51.3195 -0.0975785 50.9289 0.292946C50.5384 0.68347 50.5384 1.31664 50.9289 1.70716L56.5858 7.36401L50.9289 13.0209C50.5384 13.4114 50.5384 14.0446 50.9289 14.4351C51.3195 14.8256 51.9526 14.8256 52.3431 14.4351L58.7071 8.07112ZM0 7.36401V8.36401H58V7.36401V6.36401H0V7.36401Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Redu\u00e7\u00e3o de at\u00e9 30\u201340% nos custos cloud<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"15\" viewBox=\"0 0 59 15\" fill=\"none\"><path d=\"M58.7071 8.07112C59.0976 7.6806 59.0976 7.04743 58.7071 6.65691L52.3431 0.292946C51.9526 -0.0975785 51.3195 -0.0975785 50.9289 0.292946C50.5384 0.68347 50.5384 1.31664 50.9289 1.70716L56.5858 7.36401L50.9289 13.0209C50.5384 13.4114 50.5384 14.0446 50.9289 14.4351C51.3195 14.8256 51.9526 14.8256 52.3431 14.4351L58.7071 8.07112ZM0 7.36401V8.36401H58V7.36401V6.36401H0V7.36401Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Melhoria significativa de performance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"15\" viewBox=\"0 0 59 15\" fill=\"none\"><path d=\"M58.7071 8.07112C59.0976 7.6806 59.0976 7.04743 58.7071 6.65691L52.3431 0.292946C51.9526 -0.0975785 51.3195 -0.0975785 50.9289 0.292946C50.5384 0.68347 50.5384 1.31664 50.9289 1.70716L56.5858 7.36401L50.9289 13.0209C50.5384 13.4114 50.5384 14.0446 50.9289 14.4351C51.3195 14.8256 51.9526 14.8256 52.3431 14.4351L58.7071 8.07112ZM0 7.36401V8.36401H58V7.36401V6.36401H0V7.36401Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alta disponibilidade (99.9%+)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"15\" viewBox=\"0 0 59 15\" fill=\"none\"><path d=\"M58.7071 8.07112C59.0976 7.6806 59.0976 7.04743 58.7071 6.65691L52.3431 0.292946C51.9526 -0.0975785 51.3195 -0.0975785 50.9289 0.292946C50.5384 0.68347 50.5384 1.31664 50.9289 1.70716L56.5858 7.36401L50.9289 13.0209C50.5384 13.4114 50.5384 14.0446 50.9289 14.4351C51.3195 14.8256 51.9526 14.8256 52.3431 14.4351L58.7071 8.07112ZM0 7.36401V8.36401H58V7.36401V6.36401H0V7.36401Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Elimina\u00e7\u00e3o de gargalos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"15\" viewBox=\"0 0 59 15\" fill=\"none\"><path d=\"M58.7071 8.07112C59.0976 7.6806 59.0976 7.04743 58.7071 6.65691L52.3431 0.292946C51.9526 -0.0975785 51.3195 -0.0975785 50.9289 0.292946C50.5384 0.68347 50.5384 1.31664 50.9289 1.70716L56.5858 7.36401L50.9289 13.0209C50.5384 13.4114 50.5384 14.0446 50.9289 14.4351C51.3195 14.8256 51.9526 14.8256 52.3431 14.4351L58.7071 8.07112ZM0 7.36401V8.36401H58V7.36401V6.36401H0V7.36401Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Escalabilidade garantida<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b81344 e-con-full e-flex e-con e-parent\" data-id=\"5b81344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-109bcb7 elementor-widget elementor-widget-image\" data-id=\"109bcb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2102\" height=\"318\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/06\/wise.svg\" class=\"attachment-full size-full wp-image-1590\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db82ee1 e-flex e-con-boxed e-con e-parent\" data-id=\"db82ee1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3453db3 elementor-widget elementor-widget-heading\" data-id=\"3453db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vamos conversar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6cd88d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f6cd88d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Voc\u00ea sabe onde sua infraestrutura est\u00e1 vulner\u00e1vel hoje?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-371b44e elementor-widget elementor-widget-text-editor\" data-id=\"371b44e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O que voc\u00ea n\u00e3o enxerga no seu ambiente \u00e9 exatamente o que mais custa quando falha.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d21e0 elementor-widget elementor-widget-text-editor\" data-id=\"42d21e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Agende uma conversa com nossos especialistas e receba um diagn\u00f3stico preliminar da sua seguran\u00e7a e infraestrutura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6695d elementor-widget elementor-widget-image\" data-id=\"1b6695d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjgzMiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"63\" src=\"https:\/\/wisedb.com.br\/wp-content\/uploads\/2026\/03\/bt.svg\" class=\"elementor-animation-sink attachment-large size-large wp-image-509\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"","solucoes":[5],"class_list":["post-26","solucoes","type-solucoes","status-publish","hentry","solucoes-solucoes-em-nuvem"],"_links":{"self":[{"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/solucoes\/26"}],"collection":[{"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/solucoes"}],"about":[{"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/types\/solucoes"}],"version-history":[{"count":587,"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/solucoes\/26\/revisions"}],"predecessor-version":[{"id":1818,"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/solucoes\/26\/revisions\/1818"}],"wp:attachment":[{"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"solucoes","embeddable":true,"href":"https:\/\/wisedb.com.br\/index.php\/wp-json\/wp\/v2\/solucoes?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}